{"id":1470,"date":"2014-12-21T20:28:09","date_gmt":"2014-12-22T01:28:09","guid":{"rendered":"http:\/\/test.blackjackinfo.com\/?p=1470"},"modified":"2016-04-01T22:05:34","modified_gmt":"2016-04-02T03:05:34","slug":"neues-design-neue-wissensbasis","status":"publish","type":"post","link":"https:\/\/www.blackjackinfo.com\/de\/new-design-new-knowledge-base\/","title":{"rendered":"Ein neues Design und eine neue Wissensdatenbank"},"content":{"rendered":"<p class=\"intro\">In den letzten Monaten habe ich flei\u00dfig an dem neuen Design von BlackjackInfo gearbeitet. Und endlich ist es fertig und Sie k\u00f6nnen sich das Ergebnis ansehen.<\/p>\n<p>Die gr\u00f6\u00dfte Neuerung ist, dass sich die Website nun an das jeweilige Ger\u00e4t anpasst, so dass Sie sie auch auf Ihrem Tablet oder Mobiltelefon im Hoch- oder Querformat sehen k\u00f6nnen.<\/p>\n<p>Die beliebtesten Funktionen der Website sind nach wie vor vorhanden, darunter die <a href=\"\/blackjack-basic-strategy-engine\/\">Strategie-Engine<\/a>und eine vollst\u00e4ndige Neufassung der <a href=\"\/blackjack-rules\/\">Blackjack Regeln<\/a> Erkl\u00e4rung.<br \/>\n<!--more--><\/p>\n<h2 class=\"text-center\">Die neue Wissensdatenbank<\/h2>\n<p>Die Archive des Nachrichtenbretts wurden komplett umgestaltet und in unser neues <a href=\"\/knowledge-base\/\">Wissensdatenbank<\/a> Bereich.  Das Design stellt die Beitr\u00e4ge selbst in den Mittelpunkt, indem es alle Ablenkungen der alten Schnittstelle des Nachrichtenbretts entfernt.<\/p>\n<p>Vor allem aber habe ich viel Zeit damit verbracht, die von den Nutzern eingestellten Links zu bereinigen.  Viele n\u00fctzliche Blackjack-Links, die im Laufe der Jahre geteilt wurden, sind jetzt leider tot.  In Tausenden dieser F\u00e4lle konnte ich jedoch stattdessen auf die Kopie der Seite bei archive.org verweisen.  Sie werden also sehen, dass der ehemals tote Link jetzt auf eine archivierte Kopie verweist!  Und wo ich den Inhalt nicht retten konnte, ist der Link als toter Link vermerkt, damit Sie keine Zeit damit verschwenden, auf eine nicht existierende Seite zu klicken.<\/p>\n<p>Das Archiv der Nachrichten von CardCounter.com wurde ebenfalls wiederbelebt und neu formatiert, und die Beitr\u00e4ge erscheinen jetzt in der Wissensdatenbank in einer leicht zug\u00e4nglichen Form.   (Siehe <a href=\"\/knowledge-base\/blackjack-cc-archives\/\">Blackjack - CC-Archiv<\/a>.)<\/p>\n<h2 class=\"text-center\">Eine aufpolierte Version unserer Blackjack-Schule<\/h2>\n<p>Die Anleitungsserie zum Kartenz\u00e4hlen im GameMaster's <a href=\"\/blackjack-school\/\">Blackjack Schule<\/a> hat ein neues Aussehen erhalten, mit neuen Grafiken anstelle der Originale.  Und wie die anderen Bereiche ist auch dieser jetzt mobilfreundlich.<\/p>\n<h2 class=\"text-center\">All SSL, die ganze Zeit<\/h2>\n<p>Au\u00dferdem habe ich die gesamte Website auf \"https:\/\/\" umgestellt.  Jetzt verwendet die gesamte Website SSL und verschl\u00fcsselt Ihre gesamte Sitzung mit BlackjackInfo.  Wenn Sie nicht wollen, dass neugierige Netzwerkadministratoren sehen, welche Seiten Sie auf BJI besuchen, sind Sie jetzt v\u00f6llig sicher.<\/p>\n<h2 class=\"text-center\">Intelligentes Drucken<\/h2>\n<p>Wenn Sie einen unserer Artikel ausdrucken, werden Sie im Vergleich zu den meisten Websites eine nette \u00dcberraschung erleben.  Wenn Sie einen Artikel ausdrucken, wird das Layout f\u00fcr den Druck angepasst, wobei die gesamte Navigation und die Seitenleisten weggelassen werden.  So erhalten Sie nur die wichtigen Teile auf Papier.<\/p>\n<h2 class=\"text-center\">Mehr relevante Suchergebnisse<\/h2>\n<p>Suchen Sie etwas?  Versuchen Sie es mit dem Suchformular oben rechts in der Seitenleiste.  Ich bin noch dabei, die Relevanzsoftware zu verbessern, aber sie ist bereits sehr gut.<\/p>\n<h2 class=\"text-center\">Was halten Sie davon?<\/h2>\n<p>Schauen Sie sich um, und lassen Sie mich wissen, was Sie davon halten.  Bei der Einf\u00fchrung einer neuen Version gibt es bestimmt Dinge, die ich \u00fcbersehen habe.  Schreiben Sie mir einfach eine Antwort, wenn Sie Fragen oder Bedenken haben.<\/p>\n<p>Danke!<\/p>","protected":false},"excerpt":{"rendered":"<p>For the last few months, I have been busily working on the new design at BlackjackInfo. And finally, it&#8217;s ready to go, so you are looking at the result. The biggest enhancement is that the site now adapts to whatever device you are viewing on, so check it out on your tablet or mobile phone, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470","post","type-post","status-publish","format-standard","hentry","category-announcements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A New Design, and a New Knowledge Base<\/title>\n<meta name=\"description\" content=\"A new mobile-friendly design for the BlackjackInfo.com site is just the start. A new Knowledge Base and a revamped Blackjack School are also highlights.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/de\/neues-design-neue-wissensbasis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A New Design, and a New Knowledge Base\" \/>\n<meta property=\"og:description\" content=\"A new mobile-friendly design for the BlackjackInfo.com site is just the start. A new Knowledge Base and a revamped Blackjack School are also highlights.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/de\/neues-design-neue-wissensbasis\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-22T01:28:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-02T03:05:34+00:00\" \/>\n<meta name=\"author\" content=\"Ken Smith\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/\",\"name\":\"A New Design, and a New Knowledge Base\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2014-12-22T01:28:09+00:00\",\"dateModified\":\"2016-04-02T03:05:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\"},\"description\":\"A new mobile-friendly design for the BlackjackInfo.com site is just the start. A new Knowledge Base and a revamped Blackjack School are also highlights.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A New Design, and a New Knowledge Base\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\",\"name\":\"Ken Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"caption\":\"Ken Smith\"},\"description\":\"Creator of Blackjackinfo.com, very few can rival Ken's experience and knowledge of blackjack. His blackjack resume includes winning numerous tournament winnings, making several TV appearances and authoring multiple books on blackjack tournament strategy. Discover more about Ken's background and how he got started here\",\"sameAs\":[\"http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/\",\"https:\/\/x.com\/PlayInJersey\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein neues Design und eine neue Wissensdatenbank","description":"Ein neues, mobilfreundliches Design f\u00fcr die BlackjackInfo.com-Website ist nur der Anfang. Eine neue Wissensdatenbank und eine neu gestaltete Blackjack-Schule sind weitere Highlights.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/de\/neues-design-neue-wissensbasis\/","og_locale":"de_DE","og_type":"article","og_title":"A New Design, and a New Knowledge Base","og_description":"A new mobile-friendly design for the BlackjackInfo.com site is just the start. A new Knowledge Base and a revamped Blackjack School are also highlights.","og_url":"https:\/\/www.blackjackinfo.com\/de\/neues-design-neue-wissensbasis\/","og_site_name":"BlackjackInfo.com","article_published_time":"2014-12-22T01:28:09+00:00","article_modified_time":"2016-04-02T03:05:34+00:00","author":"Ken Smith","twitter_misc":{"Verfasst von":"Ken Smith","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/","url":"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/","name":"Ein neues Design und eine neue Wissensdatenbank","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2014-12-22T01:28:09+00:00","dateModified":"2016-04-02T03:05:34+00:00","author":{"@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71"},"description":"Ein neues, mobilfreundliches Design f\u00fcr die BlackjackInfo.com-Website ist nur der Anfang. Eine neue Wissensdatenbank und eine neu gestaltete Blackjack-Schule sind weitere Highlights.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/new-design-new-knowledge-base\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"A New Design, and a New Knowledge Base"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.de","description":"Denn Gewinnen macht mehr Spa\u00df!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71","name":"Ken Smith","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","caption":"Ken Smith"},"description":"Als Gr\u00fcnder von Blackjackinfo.com gibt es nur wenige, die mit Kens Erfahrung und Wissen \u00fcber Blackjack mithalten k\u00f6nnen. Zu seinem Blackjack-Lebenslauf geh\u00f6ren zahlreiche Turniergewinne, mehrere Fernsehauftritte und das Verfassen mehrerer B\u00fccher \u00fcber Blackjack-Turnierstrategien. Erfahren Sie hier mehr \u00fcber Kens Hintergrund und wie er angefangen hat","sameAs":["http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/","https:\/\/x.com\/PlayInJersey"]}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":18,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":1782,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/posts\/1470\/revisions\/1782"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/de\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}