{"id":1174,"date":"2020-01-08T09:10:00","date_gmt":"2020-01-08T15:10:00","guid":{"rendered":"http:\/\/test.blackjackinfo.com\/?page_id=1174"},"modified":"2020-09-02T03:06:05","modified_gmt":"2020-09-02T08:06:05","slug":"reglas-del-blackjack","status":"publish","type":"page","link":"https:\/\/www.blackjackinfo.com\/es\/blackjack-rules\/","title":{"rendered":"Blackjack de Casino: Reglas del juego"},"content":{"rendered":"<p>El juego de<br \/>\n<strong>blackjack o 21<\/strong> es el juego de mesa m\u00e1s popular que se ofrece en los casinos. Si no est\u00e1 familiarizado con las reglas<br \/>\ndel blackjack de casino o simplemente necesitas algunas aclaraciones sobre los puntos m\u00e1s delicados, \u00a1has llegado al lugar adecuado!<\/p>\n<p>Te contar\u00e9 todo lo que necesitas saber para jugar, y tambi\u00e9n te explicar\u00e9 las pocas reglas que pueden diferir de un casino a otro<br \/>\na otro.<\/p>\n<p>Si eres nuevo en los juegos de mesa de casino, puede ser un poco intimidante la primera vez que te sientes en una mesa de blackjack.<br \/>\nTodo parece ir tan r\u00e1pido y, lo que es m\u00e1s importante, \u00a1todo el mundo parece saber lo que hace!<\/p>\n<p>No se preocupe. Es muy f\u00e1cil. S\u00edgalo y sabr\u00e1 exactamente qu\u00e9 esperar en la mesa.<\/p>\n<p><!-- PART 1 --><\/p>\n<h2 id=\"blackjack-basics\" class=\"header-block\">Parte 1 - Conceptos b\u00e1sicos del Blackjack<\/h2>\n<p><!-- Premise of the Game --><\/p>\n<h3 id=\"premise-of-the-game\" class=\"font-light\">Premisa del Juego<\/h3>\n<p>El blackjack es bastante sencillo.<br \/>\n<strong>La premisa b\u00e1sica del juego es que usted quiere tener un valor de mano que est\u00e9 m\u00e1s cerca de 21 que el de la banca,<br \/>\nsin pasar de 21. Los dem\u00e1s jugadores de la mesa no le importan. Su mano s\u00f3lo compite contra la<br \/>\nmano del crupier<\/strong>.<\/p>\n<p>Las reglas de juego para el crupier est\u00e1n estrictamente dictadas, sin dejar ninguna decisi\u00f3n en manos del crupier. Por lo tanto, hay<br \/>\nning\u00fan problema con que el crupier o cualquiera de los otros jugadores de la mesa vea las cartas que tiene en la mano. De hecho, si<br \/>\nSi juegas en un zapato, las cartas de los jugadores se reparten boca arriba.<\/p>\n<p>En cualquier caso, cuando est\u00e9s aprendiendo a jugar, no dudes en mostrar al crupier o a otros jugadores tus cartas y<br \/>\nhacer preguntas.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Values of the Cards --><\/p>\n<h3 id=\"values-of-the-cards\" class=\"font-light\">Valores de las cartas<\/h3>\n<p>En el blackjack, las cartas tienen el siguiente valor:<\/p>\n<ul>\n<li><strong>Un As puede contar como 1 u 11<\/strong>como se explica a continuaci\u00f3n.<\/li>\n<li>Las cartas del 2 al 9 se valoran por su valor nominal.<\/li>\n<li>En<br \/>\n<strong>El 10, la jota, la reina y el rey tienen un valor de 10.<\/strong><\/li>\n<\/ul>\n<p><strong>Los palos de las cartas no tienen ning\u00fan significado en el juego. El valor de una mano es simplemente la suma del punto<br \/>\nrecuento de cada carta de la mano.<\/strong> Algunos ejemplos:<\/p>\n<p class=\"text-center\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/5c.gif\" alt=\"Five of Clubs\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/7h.gif\" alt=\"Seven of Hearts\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/9d.gif\" alt=\"Nine of Diamonds\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"text-center mB30\">5 + 7 + 9 = 21, por lo que esta mano tiene un valor de 21.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/jd.gif\" alt=\"Jack of Diamonds\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ts.gif\" alt=\"Ten of Spades\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"text-center mB30\">10 + 10 = 20, por lo que esta mano tiene un valor de 20.<\/p>\n<p class=\"text-center\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/9s.gif\" alt=\"Nine of Spades\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/3s.gif\" alt=\"Three of Spades\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/qh.gif\" alt=\"Queen of Hearts\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"text-center mB30\">9 + 3 + 10 = 22, por lo que esta mano es un \"busto\".<br \/>\n<strong>Cualquier mano que pase de 21 \"se rompe\", o es \"reventada\", y es una perdedora autom\u00e1tica.<\/strong><\/p>\n<p>Muy f\u00e1cil, \u00bfeh?<\/p>\n<p>El As a\u00f1ade un nuevo giro...<\/p>\n<p><strong>Un As se puede contar como 1 o como 11. No es necesario especificar qu\u00e9 valor tiene el As. Se supone que tiene<br \/>\nel valor que forma la mejor mano, y que puede cambiar a medida que se a\u00f1aden m\u00e1s cartas a la mano.<\/strong><\/p>\n<p class=\"text-center mB30\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ac.gif\" alt=\"Ace of Clubs\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/6d.gif\" alt=\"Six of Diamonds\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"text-center\">Esta mano tiene un valor de 7 \u00f3 17, tambi\u00e9n conocido como un 17 \"suave\".<\/p>\n<p><strong>Una mano blanda es cualquier mano en la que un As puede contarse como 1 u 11 sin pasar de 21. El nombre refleja<br \/>\nel hecho de que la mano no puede romperse si robas otra carta. Es \"suave\".<\/strong><\/p>\n<p class=\"text-center mB30\">Vamos a robar otra carta:<\/p>\n<p class=\"text-center\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ac.gif\" alt=\"Ace of Clubs\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/6d.gif\" alt=\"Six of Diamonds\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ks.gif\" alt=\"King of Spades\" data-no-auto-translation=\"\" \/><\/p>\n<p>Ahora nuestra mano es 17, ya que 1 + 6 + 10 = 17. Ya no tenemos la opci\u00f3n de contar el As como 11, porque eso ser\u00eda<br \/>\npasa de 21. (Esta mano es ahora un duro 17, a pesar de tener un As en ella).<\/p>\n<p class=\"text-center mB30\">Retrocedamos, y robemos una carta diferente en su lugar:<\/p>\n<p class=\"text-center\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ac.gif\" alt=\"Ace of Clubs\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/6d.gif\" alt=\"Six of Diamonds\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/3d.gif\" alt=\"Three of Diamonds\" data-no-auto-translation=\"\" \/><\/p>\n<p>Ahora nuestra mano es \"10 o 20\", un 20 suave. Veinte es una gran mano, as\u00ed que nos detendr\u00edamos all\u00ed.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Values of the Cards --><\/p>\n<h3 id=\"the-deal-of-the-cards\" class=\"font-light\">El reparto de las cartas<\/h3>\n<p>Una vez realizadas todas las apuestas, el crupier repartir\u00e1 las cartas a los jugadores. Har\u00e1 dos pases alrededor de la mesa<br \/>\nempezando por su izquierda (tu derecha) de forma que los jugadores y el crupier tengan dos cartas cada uno. El crupier<br \/>\nda la vuelta a una de sus cartas, mostrando su valor como \"carta de la banca\".<\/p>\n<p>(En algunas partes del mundo, el crupier puede recibir s\u00f3lo una carta. Hablar\u00e9 de eso dentro de un momento).<\/p>\n<p>En las partidas repartidas desde un zapato, las cartas de los jugadores estar\u00e1n boca arriba y los jugadores no podr\u00e1n tocarlas. Si<br \/>\nest\u00e1s empezando, este es el mejor tipo de juego, porque no tienes que preocuparte por el manejo de las cartas.<\/p>\n<div class=\"bji-note mB20\">\n<p>Los juegos de mano son ligeramente diferentes. En estos juegos, las cartas de los jugadores se reparten boca abajo, y los jugadores eligen<br \/>\nlas cartas. A la hora de manejar las cartas en un juego manual, hay que recordar algunas cosas importantes.<\/p>\n<ul>\n<li>S\u00f3lo debe tocar las cartas con una mano. Si usted es un jugador de p\u00f3quer, esto puede tomar un poco de esfuerzo para romper<br \/>\n\u00a1viejos h\u00e1bitos!<\/li>\n<li>Debes mantener las cartas sobre la mesa. No las acerques a tu cuerpo.<\/li>\n<li>Las cartas que el crupier reparte posteriormente en su mano se dejan sobre la mesa, no se a\u00f1aden a las cartas que usted tiene.<br \/>\nest\u00e1n sosteniendo.<\/li>\n<\/ul>\n<\/div>\n<p>Una vez repartidas las manos iniciales, el juego contin\u00faa alrededor de la mesa empezando por el primer asiento a la izquierda del crupier,<br \/>\ntambi\u00e9n llamada \"primera base\". Cada jugador, por turno, indica al crupier c\u00f3mo desea jugar la mano. (Todos los<br \/>\nesas opciones se explican en la siguiente parte de esta serie).<\/p>\n<p>Cuando todos los jugadores hayan terminado sus manos, el crupier completar\u00e1 la suya y pagar\u00e1 las apuestas ganadoras.<br \/>\ny cobrar las apuestas perdedoras.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- How the Dealer Plays His Hand --><\/p>\n<h3 id=\"how-the-dealer-plays-his-hand\" class=\"font-light\">C\u00f3mo juega la banca su mano<\/h3>\n<p>En primer lugar, el crupier dar\u00e1 la vuelta a la \"carta descubierta\" para revelar su mano inicial de dos cartas. A continuaci\u00f3n, el crupier deber\u00e1<br \/>\npara jugar su mano de una manera muy espec\u00edfica, sin opciones permitidas.<\/p>\n<p><strong>Debe robar cartas hasta que tenga un total de 17 o m\u00e1s.<\/strong> El crupier no tiene elecci\u00f3n sobre c\u00f3mo jugar la mano.<br \/>\nDebe seguir cogiendo cartas hasta que su total sea al menos 17. (M\u00e1s adelante se comenta una ligera variaci\u00f3n de esta regla).<\/p>\n<p class=\"text-center mB30\">Veamos una posible mano del crupier:<\/p>\n<p class=\"text-center mB30\"><img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/ac.gif\" alt=\"Ace of Clubs\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/5h.gif\" alt=\"Five of Hearts\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/7d.gif\" alt=\"Seven of Diamonds\" data-no-auto-translation=\"\" \/><br \/>\n<img decoding=\"async\" class=\"m10\" src=\"\/img\/cards\/6c.gif\" alt=\"Six of Clubs\" data-no-auto-translation=\"\" \/><\/p>\n<p>Despu\u00e9s de dar la vuelta a la carta descubierta, la mano del crupier era (As, 5). Eso hace un valor de mano de 16, por lo que debe robar<br \/>\notra tarjeta.<\/p>\n<p>Sac\u00f3 un 7, lo que hace que el valor de la mano sea 13 (el As ya no puede contarse como 11). Con un total de 13, debe volver a pedir carta.<\/p>\n<p>Sac\u00f3 un 6, lo que hace que el total de la mano sea 19. Como eso es \"17 o m\u00e1s\", el crupier se detiene con un total final de 19.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Wins, Losses, and Ties --><\/p>\n<h3 id=\"wins-losses-and-ties\" class=\"font-light\">Victorias, derrotas y empates<\/h3>\n<p>Una vez terminada la mano, \u00bfc\u00f3mo decide el crupier qu\u00e9 apuestas pagar y qu\u00e9 apuestas cobrar?<\/p>\n<p><strong>Si coge una carta que hace que el total de su mano sea superior a 21, su mano se pasa. Es un perdedor autom\u00e1tico. En<br \/>\nEl crupier cobrar\u00e1 inmediatamente su apuesta y descartar\u00e1 su mano.<\/strong><\/p>\n<p>Suponiendo que no te hayas pasado, el crupier jugar\u00e1 su mano al final.<br \/>\n<strong>Si se pasa de 21, todos los dem\u00e1s jugadores ganan sus apuestas.<\/strong><\/p>\n<p>Si ni t\u00fa ni el crupier os hab\u00e9is pasado, ahora el crupier comparar\u00e1 su total final con el tuyo.<\/p>\n<p>Si su total es superior al tuyo, pierdes la apuesta, y \u00e9l recoger\u00e1 tu apuesta y pondr\u00e1 las fichas en su bandeja.<\/p>\n<p>Si tu total es superior al suyo, ganas la apuesta, y \u00e9l pagar\u00e1 la cantidad total que hayas apostado. Despu\u00e9s de que pague<br \/>\nusted, tendr\u00e1 su apuesta inicial m\u00e1s la cantidad ganada en el c\u00edrculo.<\/p>\n<p>Entonces, \u00bfqu\u00e9 pasa si t\u00fa y el crupier empat\u00e1is, con el mismo total exacto? Nada.<br \/>\n<strong>Un empate se denomina \"empate\" y no se gana ni se pierde la apuesta.<\/strong> Sus fichas permanecen en el c\u00edrculo de apuestas<br \/>\ndonde puede dejarlos para la siguiente mano si lo desea, o puede a\u00f1adirlos o quitarlos a su gusto antes de<br \/>\nla siguiente mano.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- What is a Blackjack, or Natural? --><\/p>\n<h3 id=\"what-is-a-blackjack-or-natural\" class=\"font-light\">\u00bfQu\u00e9 es un Blackjack o Natural?<\/h3>\n<p><strong>Un blackjack, o natural, es un total de 21 en tus dos primeras cartas<\/strong>. Un blackjack es por tanto un As y<br \/>\ncualquier carta de valor diez, con el requisito adicional de que sean sus dos primeras cartas.<br \/>\n<strong>Si divides una pareja de ases, por ejemplo, y luego sacas una carta de valor diez en uno de los ases, no se trata de un blackjack,<br \/>\nsino un total de 21.<\/strong><\/p>\n<p>La distinci\u00f3n es importante, porque un blackjack ganador paga al jugador 3 a 2. Una apuesta de $10 gana $15 si el<br \/>\nel jugador saca un blackjack. Un blackjack de un jugador gana a cualquier otro total del crupier que no sea blackjack, incluido el del crupier.<br \/>\ntres o m\u00e1s cartas 21.<br \/>\n<strong>Si tanto un jugador como la banca tienen blackjack, la mano es un empate o push.<\/strong><\/p>\n<p>Por lo general, el crupier pagar\u00e1 su apuesta ganadora de blackjack inmediatamente cuando sea su turno de jugar. En el boca abajo<br \/>\njuegos, esto significa que debe mostrar el blackjack al crupier en ese momento. Algunos casinos pueden posponer el pago<br \/>\nel blackjack hasta que termine la mano si el crupier tiene una carta de 10 y no ha comprobado si tiene un blackjack.<br \/>\nOtros casinos pasan por debajo tanto del 10 como del As del crupier y, por lo tanto, pagar\u00edan el blackjack inmediatamente.<\/p>\n<p>En cualquier caso, cuando te repartan un blackjack, pon las cartas boca arriba y sonr\u00ede. S\u00f3lo ocurre una vez cada 21<br \/>\nmanos, pero supone gran parte de la diversi\u00f3n del juego.<\/p>\n<hr class=\"dark mB40\" \/>\n<p><!-- PART 2 --><\/p>\n<h2 id=\"player-choices\" class=\"header-block\">Parte 2 - Elecciones del jugador<\/h2>\n<p><!-- Hitting and Standing --><\/p>\n<h3 id=\"hitting-and-standing\" class=\"font-light\">Golpear y estar de pie<\/h3>\n<p>La decisi\u00f3n m\u00e1s com\u00fan que un jugador debe tomar durante el juego es si robar otra carta para la mano (\"pedir\"),<br \/>\no detenerse en el total actual (\"pararse\").<\/p>\n<p>Se le pedir\u00e1 que haga se\u00f1ales con la mano en lugar de limitarse a anunciar \"\u00e9xito\" o \"plantarse\" al crupier. Esto es para<br \/>\neliminar cualquier confusi\u00f3n o ambig\u00fcedad en lo que elija, y tambi\u00e9n en beneficio de la siempre presente vigilancia<br \/>\nc\u00e1maras. Si te pasas de 21, o te \"pasas\", el crupier recoger\u00e1 tu apuesta y retirar\u00e1 tus cartas de la mesa.<br \/>\ninmediatamente.<\/p>\n<p>La forma de se\u00f1alar tu intenci\u00f3n al croupier depende del estilo de juego que est\u00e9s jugando:<\/p>\n<h3 id=\"hand-signals-in-the-shoe-game\" class=\"mT30\">Se\u00f1ales de mano en el juego del zapato<\/h3>\n<p><strong>En el juego del zapato boca arriba, indicas que quieres otra carta golpeando la mesa detr\u00e1s de tus cartas con<br \/>\nun dedo.<\/strong><\/p>\n<p><strong>Cuando decidas plantarte, simplemente agita la mano con un movimiento horizontal sobre tus cartas.<\/strong><\/p>\n<p>Recuerda que en este estilo de juego no puedes tocar las cartas.<\/p>\n<h3 id=\"hand-signals-in-the-hand-held-game\" class=\"mT30\">Se\u00f1ales de mano en el juego manual<\/h3>\n<p>En el juego boca abajo, las cosas son un poco diferentes. Tendr\u00e1s las dos primeras cartas con una mano.<\/p>\n<p><strong>Para hacer saber al crupier que desea robar otra carta para su mano, rasque la mesa con la parte inferior de<br \/>\ntus cartas a la ligera.<\/strong> Observe a otro jugador al principio para ver c\u00f3mo funciona. El crupier repartir\u00e1 su<br \/>\ncartas adicionales sobre la mesa delante de su apuesta. Deje esas cartas sobre la mesa, pero a\u00f1\u00e1dalas mentalmente a<br \/>\nel valor total de su mano. Si te pasas de 21, simplemente tira las dos cartas de tu mano boca arriba sobre la mesa. El crupier<br \/>\nrecoger\u00e1 su apuesta y descartar\u00e1 su mano.<\/p>\n<p><strong>Cuando decida plantarse, meta las dos cartas que tiene boca abajo debajo de las fichas de su c\u00edrculo de apuestas.<\/strong><br \/>\nEsto puede ser un poco complicado las primeras veces. No levantes la apuesta para colocar las cartas debajo.<br \/>\n<strong>Recuerda, una vez repartidas las cartas, no puedes tocar las fichas del c\u00edrculo.<\/strong> Basta con deslizar la esquina<br \/>\nde las cartas bajo las fichas.<\/p>\n<p>Describir estos movimientos hace que parezcan complicados. No lo son. S\u00f3lo tienes que prestar atenci\u00f3n a lo que otros jugadores est\u00e1n haciendo<br \/>\ny encajar\u00e1s perfectamente.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Hitting and Standing --><\/p>\n<h3 id=\"doubling-down\" class=\"font-light\">Doblar la apuesta<\/h3>\n<p><strong>Gran parte de la emoci\u00f3n y los beneficios del blackjack provienen de las manos en las que puedes \"doblar\". Esta opci\u00f3n<br \/>\ns\u00f3lo est\u00e1 disponible con una mano de dos cartas, antes de que se haya robado otra carta. Doblar le permite doblar<br \/>\nsu apuesta y recibir una (y s\u00f3lo una) carta adicional a su mano.<\/strong><\/p>\n<p>Un buen ejemplo de una oportunidad de doblar es cuando tienes un total de 11, como un (6,5) contra una carta boca arriba de la banca de<br \/>\n5. En este caso, tiene muchas posibilidades de ganar la mano robando una carta m\u00e1s, por lo que deber\u00eda aumentar<br \/>\nsu apuesta en esta situaci\u00f3n ventajosa doblando.<\/p>\n<p>Si est\u00e1s jugando en un juego de mano, simplemente tira tus dos cartas originales boca arriba sobre la mesa delante de tu apuesta.<\/p>\n<p>En cualquiera de los dos tipos de juego, a\u00f1ade una apuesta adicional al c\u00edrculo de apuestas.<br \/>\n<strong>Coloca la apuesta adicional junto a la apuesta original, no encima de ella.<\/strong><\/p>\n<p>El crupier repartir\u00e1 una carta adicional en la mano. En un juego de zapato, probablemente repartir\u00e1 la carta de lado a<br \/>\nindican que se trata de una apuesta doble. En un juego de mano, la carta se colocar\u00e1 boca abajo debajo de su apuesta para<br \/>\nse revelar\u00e1 cuando termine la mano. Dependiendo de lo que el crupier haga en su mano, puede ser una espera emocionante<br \/>\n\u00a1para ver esa carta revelada al final!<\/p>\n<p>Se le permite doblar por cualquier cantidad hasta la cantidad de su apuesta original, por lo que en realidad podr\u00eda doblar por<br \/>\nmenos si quisieras. Sin embargo, es una mala jugada. Recuerde que usted renuncia a algo para que se le permita aumentar<br \/>\nsu apuesta: la posibilidad de pedir m\u00e1s de una carta adicional. Si la jugada correcta es doblar, debe<br \/>\nSiempre que sea posible, duplique el importe total.<\/p>\n<p>\u00bfY cu\u00e1ndo debes doblar la apuesta, te preguntar\u00e1s? Para saberlo, utiliza nuestro<br \/>\n<a href=\"\/blackjack-basic-strategy-engine\/\">Motor de Estrategia B\u00e1sica del Blackjack<\/a>.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Splitting Pairs --><\/p>\n<h3 id=\"splitting-pairs\" class=\"font-light\">Dividir parejas<\/h3>\n<p><strong>Cuando te reparten un par de cartas del mismo valor, puedes dividir el par en dos manos separadas<br \/>\ny reproducirlos de forma independiente.<\/strong> Digamos que te reparten una pareja de ochos para un total de diecis\u00e9is. Diecis\u00e9is<br \/>\nes la peor mano posible para un jugador, ya que es poco probable que gane tal como est\u00e1, pero es muy probable que reviente si saca<br \/>\na ella. Esta es una gran oportunidad para mejorar una mala situaci\u00f3n.<\/p>\n<p>Si est\u00e1s jugando a mano, tira las cartas boca arriba delante de tu apuesta, igual que en un double down.<br \/>\n<strong>A continuaci\u00f3n, en cualquiera de los dos tipos de juego, coloque una apuesta igual junto a la apuesta original en el c\u00edrculo. Tenga en cuenta que debe<br \/>\napostar la misma cantidad en un split, a diferencia de un double-down donde se le permite doblar por menos.<\/strong><\/p>\n<p>El crupier separar\u00e1 las dos cartas y las tratar\u00e1 como dos manos independientes. Repartir\u00e1 una segunda carta en la<br \/>\nprimer ocho, y jugar\u00e1s esa mano de dos cartas hasta completarla. (Muchos casinos le permitir\u00e1n doblar esa mano).<br \/>\nmano de dos cartas si lo desea. Hablar\u00e9 de la opci\u00f3n \"Doblar despu\u00e9s de dividir\" en<br \/>\n<a href=\"#rule-variations\">Variaciones de las reglas<\/a>.)<\/p>\n<p>No importa lo que pase en tu primera mano, cuando termines con ella el crupier repartir\u00e1 una segunda carta a tu siguiente<br \/>\nmano y el proceso vuelve a empezar.<\/p>\n<h3 id=\"resplitting\" class=\"mT30\">Volver a dividir<\/h3>\n<p><strong>Si obtiene pares adicionales en las dos primeras cartas de una mano, la mayor\u00eda de los casinos le permitir\u00e1n volver a dividir, haciendo que<br \/>\notra mano. Normalmente, un jugador puede dividir hasta 3 veces, es decir, 4 manos distintas, con 4 cartas distintas.<br \/>\napuestas. Si se permite doblar despu\u00e9s de dividir, \u00a1podr\u00eda tener hasta 8 veces su apuesta inicial en la mesa!<\/strong><\/p>\n<h3 id=\"splitting-tens\" class=\"mT30\">Dividir decenas<\/h3>\n<p><strong>Tenga en cuenta que se le permite dividir cualquier carta de valor 10, por lo que podr\u00eda dividir una mano (Jota, Reina). Sin embargo, esta<br \/>\nsuele ser una mala jugada. Mant\u00e9n los 20.<\/strong> Ganar\u00e1s m\u00e1s dinero con la pat 20 que intentando<br \/>\npara hacer dos buenas manos de \u00e9l.<\/p>\n<p>\u00bfNo te convence? Escrib\u00ed un post precisamente sobre eso:<br \/>\n<a href=\"\/why-splitting-tens-is-a-bad-move\/\">Por qu\u00e9 dividir las decenas es una mala jugada<\/a>.<\/p>\n<h3 id=\"splitting-aces\" class=\"mT30\">Dividir Ases<\/h3>\n<p>Otra rareza se produce al dividir Ases. Dividir Ases es un movimiento de jugador muy fuerte, por lo que el casino te limita a<br \/>\nrobando s\u00f3lo una carta adicional en cada As.<br \/>\n<strong>Adem\u00e1s, si sacas una carta de valor diez en uno de tus Ases divididos, la mano no se considera un Blackjack, sino que es<br \/>\nen cambio, se trata como un 21 normal y, por lo tanto, no cobra un 3:2.<\/strong><\/p>\n<p>Algunos casinos permiten volver a repartir Ases si sacas otro, pero muchos no.<\/p>\n<p>Con todas estas limitaciones, puede que te preguntes si tiene sentido dividir Ases.<\/p>\n<p>La respuesta es un rotundo<br \/>\n<strong>S\u00cd<\/strong>.<br \/>\n<strong>Dividir siempre Ases<\/strong>.<\/p>\n<p>Para obtener consejos precisos sobre qu\u00e9 otras parejas debes dividir, consulta el<br \/>\n<a href=\"\/blackjack-basic-strategy-engine\/\">Motor de Estrategia B\u00e1sica del Blackjack<\/a>.<\/p>\n<hr class=\"dark mB40\" \/>\n<p><!-- Part 3 - Basic Strategy --><\/p>\n<h2 id=\"basic-strategy\" class=\"header-block\">Parte 3 - Estrategia b\u00e1sica<\/h2>\n<p>Si quieres ganar al Blackjack, al final tendr\u00e1s que aprender la estrategia b\u00e1sica de<br \/>\n<a href=\"https:\/\/www.blackjackinfo.com\/blackjack-basic-strategy-engine\/\">un gr\u00e1fico de estrategia b\u00e1sica<\/a> o juega al<br \/>\n<a href=\"https:\/\/www.blackjackinfo.com\/blackjack-strategy-trainer\/\">entrenador de estrategia interactiva<\/a>. Sin embargo, hay algunas reglas y consejos r\u00e1pidos que puedes aprender como principiante<br \/>\npara disminuir la ventaja de la casa y formular una estrategia.<\/p>\n<h3 id=\"when-to-hit-or-stand-in-blackjack\">Cu\u00e1ndo Golpear o Plantarse en el Blackjack<\/h3>\n<ul>\n<li>1:<br \/>\n<strong>Nunca<\/strong> alcanza un duro 17 o m\u00e1s.<\/li>\n<li>2:<br \/>\n<strong>Nunca<\/strong> p\u00e1rate en un 11 o inferior.<\/li>\n<li>3:<br \/>\n<strong>Nunca<\/strong> acierta un 12-16 contra un 4, 5 \u00f3 ,6 de la banca.<\/li>\n<li>3:<br \/>\n<strong>Siempre<\/strong> acierta un 12-16 contra un 7 o m\u00e1s de la banca.<\/li>\n<li>4:<br \/>\n<strong>Siempre<\/strong> golpea en 17 suave o menos.<\/li>\n<\/ul>\n<h3 id=\"when-to-double-in-blackjack\">Cu\u00e1ndo doblar en el Blackjack<\/h3>\n<p>Recuerda que hay m\u00e1s cartas de valor 10 (10, J, Q, K) que cualquier otra carta de la baraja, as\u00ed que cuando un 10 te acerque<br \/>\na 21 y est\u00e1 en contra de una carta que es mala para la banca, deber\u00eda doblar. Un jugador 9, 10 u 11 siempre<br \/>\nser un buen doble cuando el crupier muestra un 3, 4, 5 \u00f3 6. Esto se debe a que el 3, el 4, el 5 y el 6 son cartas iniciales. Esto se debe a que el 3, 4, 5 y 6 son cartas iniciales.<br \/>\nque tienen m\u00e1s probabilidades de hacer que el crupier se pase.<\/p>\n<ul>\n<li>1:<br \/>\n<strong>Siempre<\/strong> dobla un 9 contra un 3, 4, 5 \u00f3 6.<\/li>\n<li>2:<br \/>\n<strong>Siempre<\/strong> dobla un 10 contra cualquier carta del repartidor que no sea un 10 o un As.<\/li>\n<li>3:<br \/>\n<strong>Siempre<\/strong> dobla un 11 contra cualquier carta del repartidor que no sea un As.<\/li>\n<li>3:<br \/>\n<strong>Siempre<\/strong> dobla un 18 suave o inferior contra un 5 o 6.<\/li>\n<\/ul>\n<h3 id=\"when-to-split-in-blackjack\">Cu\u00e1ndo dividir en el Blackjack<\/h3>\n<p><strong>1: Divide siempre Ases y Ochos.<\/strong><\/p>\n<p>El As es una carta tan poderosa porque sacar un 10 en una divisi\u00f3n te dar\u00e1 un 21. A pesar de que un 21 obtenido a trav\u00e9s de una divisi\u00f3n<br \/>\nse sigue pagando s\u00f3lo 1:1, es una situaci\u00f3n muy ventajosa. Dividir 8's es importante porque te libra de<br \/>\nun 16, la peor mano del Blackjack.<\/p>\n<p><strong>2: Nunca repartas cincos o caras.<\/strong><\/p>\n<p>Dos cincos suman 10, que es una mano mucho m\u00e1s adecuada para doblar. Las cartas con caras o los 10 no se deben dividir porque ya<br \/>\ntotal 20, que es una gran mano por s\u00ed sola.<\/p>\n<hr class=\"dark mB40\" \/>\n<p><!-- PART 4 --><\/p>\n<h2 id=\"insurance-and-surrender\" class=\"header-block\">Parte 4 - Seguro y rescate<\/h2>\n<p><!-- Hitting and Standing --><\/p>\n<h3 id=\"insurance\" class=\"font-light\">Seguros<\/h3>\n<p>El seguro en el blackjack es a menudo malinterpretado por los jugadores, y es un gran generador de dinero para los casinos. El nombre de esta apuesta lateral<br \/>\nEl \"seguro\" fue una brillante estratagema de marketing, y algunos jugadores por lo dem\u00e1s s\u00f3lidos har\u00e1n con frecuencia esta mala apuesta<br \/>\npara \"asegurarse\" cuando tienen una buena mano. Pero, en realidad, asegurarse no siempre es una mala apuesta. Para los jugadores que pueden<br \/>\nreconocer cuando la baraja restante es rica en cartas de valor diez, esto puede ser realmente una apuesta lateral rentable.<\/p>\n<p>Entonces, \u00bfqu\u00e9 es exactamente el \"seguro\" en el blackjack?<\/p>\n<p><strong>El seguro es una apuesta de proposici\u00f3n que s\u00f3lo est\u00e1 disponible cuando la carta descubierta del crupier es un As.<\/strong><\/p>\n<p>Cuando el crupier saca un As, ofrece un \"Seguro\" a los jugadores. Las apuestas de seguro se pueden hacer apostando<br \/>\nhasta la mitad del importe de su apuesta original en la franja de apuesta de seguro situada delante de su apuesta.<\/p>\n<p>El crupier comprobar\u00e1 si tiene una carta de valor 10 debajo de su As, y si tiene Blackjack, tu ganancia ser\u00e1<br \/>\nLa apuesta de seguro se pagar\u00e1 a una cuota de 2:1. Seguir\u00e1 perdiendo su apuesta original (a menos que tambi\u00e9n tenga un Blackjack),<br \/>\npor lo que el efecto neto es que se llega al punto de equilibrio (suponiendo que se apueste la mitad completa de la apuesta como seguro).<br \/>\nse describe como \"seguro\", ya que parece proteger su apuesta original contra un blackjack del crupier. Por supuesto,<br \/>\nsi el crupier no tiene blackjack, perder\u00e1 la apuesta de seguro y tendr\u00e1 que jugar la apuesta original<br \/>\nfuera.<\/p>\n<p><strong>El seguro es simplemente una apuesta lateral que ofrece probabilidades de 2:1 de que el crupier tenga una carta de valor 10 debajo de su As.<\/strong><br \/>\nNo es sorprendente que el casino tenga una ventaja sustancial en esta apuesta. En un juego de una sola baraja, hay 16 cartas de valor diez. Suponiendo que<br \/>\nque no veas ninguna otra carta, incluida la tuya, los dieces componen 16 de las 51 cartas restantes despu\u00e9s del<br \/>\nEl as del crupier fue retirado. Para que la apuesta de seguro sea una apuesta de equilibrio, la carta descubierta tendr\u00eda que ser un diez.<br \/>\n1 de cada 3 veces, pero 16\/51 es s\u00f3lo 1 de cada 3,1875.<\/p>\n<p>Esto crea una ventaja de la casa de 5,88% en la apuesta de seguro en una sola baraja. Es incluso peor en seis barajas con una ventaja de la casa de 7,40%.<br \/>\nborde.<\/p>\n<p>Los contadores de cartas todav\u00eda pueden superar la apuesta de seguro, haciendo la apuesta s\u00f3lo cuando saben que m\u00e1s de un tercio de<br \/>\nlas cartas restantes son dieces.<\/p>\n<p>A menos que seas un contador de cartas y sepas que la baraja est\u00e1 lo suficientemente sesgada, simplemente ignora la apuesta de seguro. No importa<br \/>\ntanto si tienes una buena como una mala mano.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Splitting Pairs --><\/p>\n<h3 id=\"taking-even-money-on-blackjack\" class=\"font-light\">Ganar \"incluso dinero\" en el Blackjack<\/h3>\n<p>Si tienes un blackjack y el crupier saca un as, es probable que te ofrezca \"dinero parejo\" en lugar del seguro.<br \/>\napuesta. Si acepta, el crupier le pagar\u00e1 el importe de su apuesta original y descartar\u00e1 su mano de blackjack,<br \/>\nantes incluso de comprobar bajo su As si tambi\u00e9n tiene un Blackjack.<\/p>\n<p>Muchos jugadores piensan que esto suena como un buen trato, garantizando un beneficio incluso si el crupier tiene un blackjack. Pero eso<br \/>\nEl beneficio garantizado tiene un precio. Ganar\u00e1s m\u00e1s dinero a largo plazo si esperas a recibir el pago completo del $15.<br \/>\ncuando el crupier no tiene blackjack, aunque a veces acabe con las manos vac\u00edas.<\/p>\n<p>\"Even money\" no es m\u00e1s que una apuesta de seguro en tu blackjack, ni m\u00e1s ni menos. Le mostrar\u00e9 c\u00f3mo<br \/>\nfunciona:<\/p>\n<p>Digamos que apuestas $10, y tienes un Blackjack. Normalmente cobrar\u00eda $15 por esto, a menos que el crupier tambi\u00e9n tenga<br \/>\nun blackjack, en cuyo caso se pasa o se empata. Supongamos que el crupier tiene un as, y usted decide tomar<br \/>\nseguro por el importe total permitido de $5.<\/p>\n<p>Ahora bien, pueden ocurrir dos cosas:<\/p>\n<ol>\n<li>El crupier tiene un Blackjack. Empatas con el $10, pero cobras 2:1 en la apuesta de seguro $5 para un beneficio total.<br \/>\nde $10.<\/li>\n<li>El crupier no tiene Blackjack. Pierdes la apuesta de seguro de $5, pero cobras $15 por tu Blackjack. Su total<br \/>\nbeneficio es de nuevo $10.<\/li>\n<\/ol>\n<p>En cualquiera de los dos casos, una vez realizada la apuesta de seguro, tiene garantizado un beneficio de $10, lo que supone un pago igualado<br \/>\nde su apuesta original. Por lo tanto, los casinos le permiten eliminar la apuesta de seguro por completo, y simplemente declarar que<br \/>\nquieres \"dinero parejo\" para tu blackjack cuando la banca tiene un As.<\/p>\n<p>El problema es que sigue haciendo una mala apuesta en materia de seguros, que le cuesta dinero. Si ignora la oferta de<br \/>\nincluso dinero, a veces obtienes $15, y a veces obtienes $0. Pero por t\u00e9rmino medio, cobrar\u00e1 algo m\u00e1s de<br \/>\nel $10 que le ofrecen por dinero parejo.<\/p>\n<p>Un jugador que no cuente cartas simplemente nunca deber\u00eda aceptar la apuesta de seguro, ni siquiera la variedad de \"dinero parejo\".<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Splitting Pairs --><\/p>\n<h3 id=\"surrender\" class=\"font-light\">R\u00edndete<\/h3>\n<p><strong>Algunos juegos ofrecen al jugador la posibilidad de retirarse y perder la mitad de su apuesta. Esta opci\u00f3n de rendirse<br \/>\ndebe realizarse como primera acci\u00f3n del jugador en la mano.<\/strong> En otras palabras, no puedes dibujar<br \/>\nuna tarjeta y luego deciden abandonar.<\/p>\n<p>Incluso cuando existe la posibilidad de rendirse, los jugadores rara vez la utilizan. A menudo, las reglas publicadas en la mesa no mencionan<br \/>\nincluso si el casino lo permite. Y a muchos jugadores simplemente no les gusta la idea de rendirse en una mano. Pero para un<br \/>\njugador inteligente, es una opci\u00f3n \u00fatil, y reduce la ventaja de la casa en aproximadamente 0,08%.<\/p>\n<p>Cuando est\u00e9 disponible la opci\u00f3n de rendirse, aseg\u00farese de conocer la estrategia correcta para utilizarla. La mayor\u00eda de los jugadores que utilizan la opci\u00f3n<br \/>\nrendirse demasiadas manos. Si su juego ofrece la posibilidad de rendirse, le recomiendo que lea mi<br \/>\n<a href=\"\/blackjack-surrender-explained\/\">explicaci\u00f3n completa de la rendici\u00f3n en el blackjack<\/a>.<\/p>\n<p>En la variedad m\u00e1s com\u00fan (conocida como rendici\u00f3n \"tard\u00eda\"), un jugador no puede rendirse hasta despu\u00e9s de que el crupier haya pasado.<br \/>\npara el blackjack. Si el crupier tiene blackjack, perder\u00e1 toda su apuesta sin posibilidad de rendirse por<br \/>\nla mitad del coste.<\/p>\n<hr class=\"dark mB40\" \/>\n<p><!-- PART 4 --><\/p>\n<h2 id=\"rule-variations\" class=\"header-block\">Parte 5 - Variaciones de las reglas<\/h2>\n<p>Hay algunas reglas en el blackjack que pueden variar ligeramente de un casino a otro.<\/p>\n<p><!-- Dealer Hits Soft 17 --><\/p>\n<h3 id=\"dealer-hits-soft-17\" class=\"font-light\">La banca acierta un 17 suave<\/h3>\n<p>Por lo general, el crupier en el blackjack debe pedir carta si tiene un total de 16 o menos, y plantarse si tiene 17 o m\u00e1s.<\/p>\n<p>Pero en algunos juegos hay una excepci\u00f3n cuando el crupier tiene una mano de 17 \"suave\".<\/p>\n<p>Si miras a la mesa, ver\u00e1s una de las dos frases en el fieltro:<\/p>\n<ul>\n<li><strong>El crupier se planta con todos los 17<\/strong>: Esta es la versi\u00f3n simple. El crupier se plantar\u00e1 con cualquier total de 17<br \/>\no m\u00e1s, tanto si ese total es \"blando\" como si no. (Esta regla se abrevia S17. \u00a1La S es de Stand, no de Soft!).<\/li>\n<li><strong>La banca acierta un 17 suave<\/strong>: En los casinos con esta regla, el crupier se plantar\u00e1 con cualquier 17 duro, pero sacar\u00e1<br \/>\notra carta si tiene un 17 suave, como (As, 2, 4). (Esta regla se abrevia H17).<\/li>\n<\/ul>\n<p>Diecisiete es una mano d\u00e9bil, por lo que si se permite que el crupier intente mejorar las manos suaves de 17, el juego se vuelve m\u00e1s dif\u00edcil.<br \/>\nCuando se permite que un crupier obtenga un 17 blando, la ventaja de la casa aumenta aproximadamente 0,2%.<\/p>\n<p>Hace a\u00f1os, los \u00fanicos juegos \"Hit Soft 17\" en EE.UU. se celebraban en Reno, Nevada, y sus alrededores. Casi todas las dem\u00e1s zonas utilizaban el<br \/>\nmejor regla de plantarse en todos los 17s. Con los a\u00f1os, m\u00e1s y m\u00e1s casinos han cambiado a golpear suave 17, y<br \/>\nahora hay muchos m\u00e1s juegos H17 que S17.<\/p>\n<p>Todav\u00eda se pueden encontrar algunos juegos en los que el crupier se planta en todos los 17s, incluso en casinos en los que algunas de las mesas utilizan el<br \/>\nRegla H17. \u00a1Mira a tu alrededor!<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Double After Split --><\/p>\n<h3 id=\"double-after-split\" class=\"font-light\">Doble despu\u00e9s de dividir<\/h3>\n<p><strong>Despu\u00e9s de dividir una pareja, muchos casinos le permitir\u00e1n doblar una mano de dos cartas que surja como resultado.<br \/>\nde la divisi\u00f3n.<\/strong> Por ejemplo, si divides una pareja de ochos, y sacas un 3 en la primera mano, es<br \/>\nvalioso para poder doblar en la mano resultante de 11.<\/p>\n<p>Esta regla es bastante com\u00fan, y ayuda al jugador en aproximadamente 0,12%.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Resplitting Aces --><\/p>\n<h3 id=\"resplitting-aces\" class=\"font-light\">Volver a repartir ases<\/h3>\n<p>Como se mencion\u00f3 en la secci\u00f3n anterior sobre la divisi\u00f3n de pares, existen varias restricciones comunes a la divisi\u00f3n<br \/>\nAses. Usted recibir\u00e1 s\u00f3lo una carta en cada As despu\u00e9s de dividir.<\/p>\n<p><strong>Algunos casinos le permitir\u00e1n volver a dividir si saca otro As, y otros no. Esto es cierto incluso si el casino<br \/>\npermite el desdoblamiento de todos los dem\u00e1s pares.<\/strong><\/p>\n<p>Cuando el casino permite volver a repartir Ases, ayuda al jugador en aproximadamente 0,08%.<\/p>\n<p>Esta regla rara vez se indica en la mesa. Si tiene curiosidad, tendr\u00e1 que preguntar al crupier.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Peek or No-Peek, Hole Card or No Hole Card --><\/p>\n<h3 id=\"peek-or-no-peek-hole-card-or-no-hole-card\" class=\"font-light\">Peek o No-Peek, Hole Card o No Hole Card<\/h3>\n<p>Muchos casinos en Europa, y algunos en otras partes del mundo, manejan la segunda carta del crupier de forma diferente.<br \/>\n<strong>En estos juegos \"European No Hole Card\", el crupier s\u00f3lo se reparte una carta al principio de la ronda.<br \/>\nDespu\u00e9s de que todos los jugadores hayan completado sus manos, reparte su propia segunda carta y completa la mano.<\/strong><\/p>\n<p>Contrasta eso con el estilo de juego normal de EEUU.<br \/>\n<strong>All\u00ed, si el crupier tiene una carta de diez o un as, comprueba inmediatamente la otra carta para ver si tiene un blackjack.<br \/>\nSi lo hace, se acab\u00f3 la mano.<\/strong> Este proceso de \"mirar\" por debajo de la carta descubierta para comprobar si hay blackjack<br \/>\nsignifica que los jugadores s\u00f3lo pueden perder una apuesta por mano si el crupier tiene un blackjack.<\/p>\n<p>En una partida sin cartas, un jugador puede dividir o doblar y arriesgar varias apuestas a un blackjack del crupier, porque<br \/>\nel crupier no puede comprobarlo de antemano. Esto cambia la estrategia \u00f3ptima, y significa que los jugadores deber\u00edan normalmente<br \/>\nno dividir ni doblar contra un diez o un as de la banca. (Una excepci\u00f3n es dividir ases contra un diez del crupier).<\/p>\n<p>Tenga en cuenta que hay algunos juegos de cartas sin agujero en los que las reglas dicen espec\u00edficamente que s\u00f3lo se cobrar\u00e1 una apuesta<br \/>\nde un jugador si la banca tiene un blackjack. En esos juegos, aunque no haya carta de mano, se puede jugar el<br \/>\njuego como si lo hubiera. (Eso significa que debes jugarlo como un juego de Peek, \u00a1aunque en realidad no haya un peek!).<br \/>\nEs todo un poco confuso.<\/p>\n<p>Cuando se utiliza la regla de No-Hole-Card, y todas las apuestas est\u00e1n en riesgo ante un blackjack del crupier,<br \/>\n<strong>cuesta al jugador 0,11%<\/strong>y los jugadores deben revisar su estrategia en consecuencia. (Utilice el \"No-Peek\"<br \/>\nen nuestra<br \/>\n<a href=\"\/blackjack-basic-strategy-engine\/\">Motor de estrategia<\/a>.)<\/p>\n<hr class=\"dotted mB40\" \/>\n<h3 class=\"font-light\">Las Cinco Cartas Charlie<\/h3>\n<p>Ok, esta es una variaci\u00f3n extremadamente rara que dudo que veas en ning\u00fan casino hoy en d\u00eda, pero pens\u00e9 en mencionarlo. Si el<br \/>\nel jugador coge 5 cartas y no se pasa, entonces gana autom\u00e1ticamente la mano (esto se llama \"Charlie\").<\/p>\n<p>Del mismo modo, existe una variaci\u00f3n de la regla por la que el jugador gana autom\u00e1ticamente cuando roba 7 cartas sin pasarse, que se denomina<br \/>\na \"Seven Card Charlie\".<\/p>\n<hr class=\"dotted\" \/>\n<p><!-- PART 6 --><\/p>\n<div id=\"casino-basics\">\n<h2 id=\"part-6-playing-at-the-casino-basics\" class=\"header-block\">Parte 6 - Aspectos b\u00e1sicos del juego en el casino<\/h2>\n<p><!-- Choosing a table --><\/p>\n<h3 id=\"choosing-a-table\" class=\"font-light\">Elegir una mesa en el casino<\/h3>\n<p>Si eres nuevo en el juego, hay algunos elementos en los que debes fijarte cuando busques...<\/p>\n<p>El elemento m\u00e1s importante es el cartel que declara los l\u00edmites de las apuestas. Si est\u00e1 leyendo esto, probablemente no quiera<br \/>\n\u00a1sentarse en una mesa que exija una apuesta m\u00ednima de $100! Tanto la apuesta m\u00ednima como la m\u00e1xima permitidas deben<br \/>\nestar en un cartel en el tablero de la mesa. Busque una mesa que se adapte al tama\u00f1o de sus apuestas.<\/p>\n<p>Aseg\u00farese de que la mesa que ha seleccionado es realmente para blackjack, y no otro de los muchos tipos de mesa<br \/>\njuegos que ofrecen los casinos. Busque en la mesa la frase \"<br \/>\n<i>El Blackjack se paga 3 a 2<\/i>\u201c.<br \/>\n<strong>Evite cualquier juego que diga \"<br \/>\n<i>El blackjack se paga de 6 a 5<\/i>\" en su lugar<\/strong>. (V\u00e9ase<br \/>\n<a href=\"\/no-6-to-5-blackjack\/\">\u00bfBlackjack 6 a 5? \u00a1Di que no!<\/a>.)<\/p>\n<p>A continuaci\u00f3n, observe c\u00f3mo se reparte el juego. Hay dos estilos diferentes de repartir:<\/p>\n<ul>\n<li><strong>Juegos de zapatos<\/strong>: El crupier distribuye las cartas de un zapato de repartir y las cartas de los jugadores se reparten todas<br \/>\nboca arriba. Estos juegos suelen utilizar 6 u 8 barajas de cartas.<\/li>\n<li><strong>Juegos port\u00e1tiles<\/strong>: El crupier tiene las cartas en la mano y suele repartir las cartas del jugador boca abajo.<br \/>\nEstos juegos suelen utilizar 1 o 2 barajas de cartas.<\/li>\n<\/ul>\n<p><strong>Los principiantes deber\u00edan empezar jugando a los juegos de zapatos<\/strong>. La ventaja de este estilo es que todos los jugadores<br \/>\nLas cartas se reparten boca arriba, por lo que el crupier y los dem\u00e1s jugadores pueden ayudarle f\u00e1cilmente con sus preguntas y decisiones de juego.<br \/>\nUna vez que domines el juego, es posible que quieras cambiar a un juego con menos barajas, ya que eso reduce el<br \/>\nventaja del casino.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Buying Chips --><\/p>\n<h3 id=\"buying-chips\" class=\"font-light\">Comprar patatas fritas<\/h3>\n<p>Para jugar, tendr\u00e1 que cambiar algo de dinero por fichas del crupier.<\/p>\n<p>Espere a una pausa en la acci\u00f3n y coloque su dinero delante de usted en el fieltro de la mesa.<\/p>\n<p>Aqu\u00ed se aplican algunos puntos de etiqueta:<\/p>\n<ul>\n<li><strong>No intentes entregarle tu dinero al croupier. Por motivos de seguridad, no puede quitarte nada de las manos.<br \/>\nD\u00e9jalo sobre la mesa.<\/strong><\/li>\n<li><strong>No lo pongas en el c\u00edrculo de apuestas, ya que algunos casinos permiten apuestas en efectivo, y el crupier puede pensar que t\u00fa<br \/>\n\u00a1quiero apostarlo todo!<\/strong><\/li>\n<li><strong>Compra al menos el dinero suficiente para jugar varias manos. Un jugador t\u00edpico de $5 podr\u00eda apostar $40 m\u00e1s o menos.<\/strong><\/li>\n<\/ul>\n<p>El crupier cambiar\u00e1 la cantidad total de dinero en efectivo por el equivalente en fichas, y depositar\u00e1 el dinero en efectivo en una caja situada en el tablero.<br \/>\nmesa.<\/p>\n<p>Echa un vistazo r\u00e1pido a las fichas para asegurarte de que conoces el valor de cada color.<br \/>\n<strong>Los colores de chip habituales son rojo para $5, verde para $25 y negro para $100.<\/strong><\/p>\n<p>Si tienes alguna duda, pregunta al crupier. Parte de su trabajo consiste en ayudar a los jugadores a aprender el juego.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Placing a Bet --><\/p>\n<h3 id=\"placing-a-bet\" class=\"font-light\">Hacer una apuesta<\/h3>\n<p>Una vez que est\u00e9 listo para realizar una apuesta, espere a que se complete la mano actual y, a continuaci\u00f3n, introduzca su apuesta en la quiniela.<br \/>\nc\u00edrculo.<\/p>\n<p><strong>Sus fichas deben estar en una sola pila. Si est\u00e1 apostando m\u00faltiples denominaciones de fichas, coloque las de mayor valor<br \/>\nen la parte inferior de la pila, y las fichas de menor valor en la parte superior.<\/strong><\/p>\n<p>Una vez repartidas las cartas, no est\u00e1 permitido tocar la apuesta en el c\u00edrculo. Si necesita saber cu\u00e1nto<br \/>\nha apostado para doblar o dividir (se explica m\u00e1s adelante), el crupier contar\u00e1 las fichas por usted.<\/p>\n<p>Una vez terminada la mano, el crupier se desplazar\u00e1 por la mesa a cada posici\u00f3n por turnos, pagando las manos ganadoras y cobrando<br \/>\nlas fichas de las manos perdedoras.<br \/>\n<strong>Despu\u00e9s de que el crupier le haya pagado, puede retirar sus fichas del c\u00edrculo y realizar su siguiente apuesta.<\/strong><\/p>\n<p><strong>Si quiere dejar correr sus ganancias, tendr\u00e1 que formar una pila de fichas a partir de las dos o m\u00e1s pilas de<br \/>\nla mesa despu\u00e9s de que el crupier le pague. Recuerde que las fichas de mayor valor deben colocarse en la parte inferior de la pila.<br \/>\n<\/strong><\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Cashing Your Chips --><\/p>\n<h3 id=\"cashing-your-chips\" class=\"font-light\">Cobrar tus fichas<\/h3>\n<p>Cuando est\u00e9 listo para abandonar la mesa, no canjee sus fichas de la misma forma en que las compr\u00f3.<br \/>\n<strong>El crupier no puede darte dinero en efectivo por las fichas en la mesa. Para ello, debe llevar las fichas al casino<br \/>\nCajero.<br \/>\n<\/strong><\/p>\n<p><strong>Si tienes muchas fichas de baja denominaci\u00f3n delante de ti en la mesa, deber\u00edas cambiarlas por el equivalente<br \/>\nfichas de mayor valor. Entre manos, simplemente dile al crupier que quieres \"colorear\", y \u00e9l tendr\u00e1<br \/>\nempujas tus fichas al centro de la mesa.<\/strong> Las contar\u00e1 y te dar\u00e1 una menor<br \/>\nUna pila de fichas del mismo valor. Esto hace que sean m\u00e1s f\u00e1ciles de transportar para usted y para el crupier.<br \/>\nmantiene su suministro de fichas m\u00e1s peque\u00f1as.<\/p>\n<p>Ahora puedes llevarte esas fichas a otra mesa para seguir jugando, o dirigirte al cajero del casino, donde podr\u00e1s cambiarlas por monedas.<br \/>\npor dinero.<\/p>\n<hr class=\"dotted mB40\" \/>\n<\/div>\n<div id=\"faq\">\n<h2 class=\"font-light header-block\">PREGUNTAS FRECUENTES<\/h2>\n<div class=\"casino-faq-container\"> <button class=\"faq-accordion\">\u00bfLos palos de las cartas marcan la diferencia?<\/button><\/p>\n<div class=\"faq-panel\">\n<div class=\"faq-answer\">\n<p> En absoluto. A diferencia de otros juegos de cartas, los palos no intervienen en absoluto en la evaluaci\u00f3n de las cartas.\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"casino-faq-container\"> <button class=\"faq-accordion\">\u00bfEs legal contar cartas?<\/button><\/p>\n<div class=\"faq-panel\">\n<div class=\"faq-answer\">\n<p>\u00a1S\u00ed!  Lee nuestro <a href=\"https:\/\/www.blackjackinfo.com\/card-counting\/\">art\u00edculo sobre el conteo de cartas<\/a> para m\u00e1s informaci\u00f3n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<hr class=\"dotted mB40\"><\/div>\n<div id=\"what-next\">\n<p><!-- What's Next --><\/p>\n<h2 id=\"whats-next\" class=\"font-light header-block\">El futuro<\/h2>\n<p>Si ha llegado hasta aqu\u00ed, enhorabuena. Deber\u00eda tener una buena idea de lo que le espera cuando se siente...<br \/>\nen una mesa de blackjack en el casino.<\/p>\n<p>De lo que no hemos hablado es de c\u00f3mo tomar las mejores decisiones mientras se juega. Eso es todo un<br \/>\ntema en s\u00ed mismo. Para tener las mayores posibilidades de ganar, debe aprender y practicar la \"estrategia b\u00e1sica\", que<br \/>\nes la mejor manera matem\u00e1tica de jugar cada mano contra cada posible carta ascendente del crupier.<\/p>\n<p>Para obtener un gr\u00e1fico gratuito que muestra la jugada correcta en cada caso, visita nuestro<br \/>\n<a href=\"\/blackjack-basic-strategy-engine\/\">Motor de Estrategia B\u00e1sica del Blackjack<\/a>.<\/p>\n<p>Vas por buen camino.<\/p>\n<hr class=\"dotted mB40\" \/>\n<p><!-- Play Online for Real Money --><\/p>\n<h2 id=\"play-online-for-real-money\" class=\"font-light\">Juega en l\u00ednea con dinero real<\/h2>\n<p>Si quieres jugar desde la comodidad de tu casa, puedes visitar nuestro<br \/>\n<a href=\"\/online-blackjack\/\">blackjack online<\/a> o<br \/>\n<a href=\"https:\/\/www.blackjackinfo.com\/live-dealer-blackjack\/\">blackjack con crupier en vivo<\/a> para obtener m\u00e1s recursos.<\/p>\n<hr class=\"dotted mB30\" \/>\n<p>Espero haber cubierto casi todo lo que necesitas. Pero si tienes otras preguntas, no dudes en responder.<br \/>\nen la parte inferior de la p\u00e1gina.<\/p>\n<p>Mientras est\u00e1s aqu\u00ed, echa un vistazo a algunas de nuestras funciones m\u00e1s populares:<\/p>\n<hr class=\"dotted mB40 mT30\" \/>\n<p class=\"text-center\"><a href=\"\/blackjack-strategy-trainer\/\"><br \/>\n<img decoding=\"async\" class=\"\" src=\"\/files\/Trainer-300x218.gif\" alt=\"Blackjack Strategy Trainer\" data-no-auto-translation=\"\" \/><br \/>\n<\/a><\/p>\n<p class=\"text-center mB30\">\u00bfQuieres practicar? Nuestra<br \/>\n<a href=\"\/blackjack-strategy-trainer\/\">juego de blackjack gratis<\/a> te permite jugar a tu ritmo, y el Entrenador de Estrategia te proporciona informaci\u00f3n instant\u00e1nea sobre las mejores<br \/>\nestrategia.<\/p>\n<p class=\"text-center\"><a href=\"\/blackjack-basic-strategy-engine\/\"><br \/>\n<img decoding=\"async\" class=\"\" src=\"\/files\/Chart.gif\" alt=\"Strategy Chart\" data-no-auto-translation=\"\" \/><br \/>\n<\/a><\/p>\n<p class=\"text-center\">Para encontrar la mejor estrategia, utilice nuestro recurso m\u00e1s popular: El sitio<br \/>\n<a href=\"\/blackjack-basic-strategy-engine\/\">Motor de estrategia de Blackjack<\/a> proporciona gr\u00e1ficos de estrategia gratuitos optimizados para tus reglas exactas.<\/p>\n<p class=\"text-center\">Si prefiere una tarjeta de pl\u00e1stico que pueda llevarse a la mesa, tambi\u00e9n disponemos de ellas:<br \/>\n<a href=\"\/card\/\">Cartas de Estrategia B\u00e1sica de Blackjack.<\/a><\/p>\n<div class=\"bji-note mB20\"><\/div>\n<p><!-- END OF LISTING --><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>The game of blackjack or 21 is the most popular table game offered in casinos. If you are unfamiliar with the rules of casino blackjack or simply need some clarification on the finer points, you\u2019ve come to the right place! I will tell you everything you need to know to play the game, and also [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"page-blackjack-rules-new.php","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-1174","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blackjack Rules - Learn How to Play Blackjack in 6 Easy Steps<\/title>\n<meta name=\"description\" content=\"Blackjack is a simple game, but there are a lot of details among the rules. We break this down into steps which will teach you what to expect at the casino.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/es\/reglas-del-blackjack\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blackjack Rules - Learn How to Play Blackjack in 6 Easy Steps\" \/>\n<meta property=\"og:description\" content=\"Blackjack is a simple game, but there are a lot of details among the rules. We break this down into steps which will teach you what to expect at the casino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/es\/reglas-del-blackjack\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-02T08:06:05+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"29 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/blackjack-rules\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/blackjack-rules\/\",\"name\":\"Blackjack Rules - Learn How to Play Blackjack in 6 Easy Steps\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2020-01-08T15:10:00+00:00\",\"dateModified\":\"2020-09-02T08:06:05+00:00\",\"description\":\"Blackjack is a simple game, but there are a lot of details among the rules. We break this down into steps which will teach you what to expect at the casino.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/blackjack-rules\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/blackjack-rules\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/blackjack-rules\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casino Blackjack: Rules of the Game\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reglas del Blackjack - Aprende a jugar al Blackjack en 6 sencillos pasos","description":"El blackjack es un juego sencillo, pero hay muchos detalles entre las reglas. Lo desglosamos en pasos que te ense\u00f1ar\u00e1n qu\u00e9 puedes esperar en el casino.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/es\/reglas-del-blackjack\/","og_locale":"es_ES","og_type":"article","og_title":"Blackjack Rules - Learn How to Play Blackjack in 6 Easy Steps","og_description":"Blackjack is a simple game, but there are a lot of details among the rules. We break this down into steps which will teach you what to expect at the casino.","og_url":"https:\/\/www.blackjackinfo.com\/es\/reglas-del-blackjack\/","og_site_name":"BlackjackInfo.com","article_modified_time":"2020-09-02T08:06:05+00:00","twitter_misc":{"Tiempo de lectura":"29 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/blackjack-rules\/","url":"https:\/\/www.blackjackinfo.com\/blackjack-rules\/","name":"Reglas del Blackjack - Aprende a jugar al Blackjack en 6 sencillos pasos","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2020-01-08T15:10:00+00:00","dateModified":"2020-09-02T08:06:05+00:00","description":"El blackjack es un juego sencillo, pero hay muchos detalles entre las reglas. Lo desglosamos en pasos que te ense\u00f1ar\u00e1n qu\u00e9 puedes esperar en el casino.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/blackjack-rules\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/blackjack-rules\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/blackjack-rules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"Casino Blackjack: Rules of the Game"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"\u00a1Porque ganar es m\u00e1s divertido!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/pages\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":97,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/pages\/1174\/revisions"}],"predecessor-version":[{"id":5439,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/pages\/1174\/revisions\/5439"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}