{"id":1611,"date":"2015-09-15T22:12:46","date_gmt":"2015-09-16T03:12:46","guid":{"rendered":"https:\/\/www.blackjackinfo.com\/?p=1611"},"modified":"2016-01-30T18:14:50","modified_gmt":"2016-01-31T00:14:50","slug":"por-que-importa-el-numero-de-barajas-en-el-blackjack","status":"publish","type":"post","link":"https:\/\/www.blackjackinfo.com\/es\/why-does-the-number-of-decks-matter-in-blackjack\/","title":{"rendered":"\u00bfPor qu\u00e9 es importante el n\u00famero de barajas en el Blackjack?"},"content":{"rendered":"<h2 style=\"text-align: center;\">Menos cubiertas es mejor.  \u00bfSabe por qu\u00e9?<\/h2>\n<p>Cuando se trata del n\u00famero de barajas en una partida de blackjack, cuantas menos mejor.  La mayor\u00eda de los jugadores han o\u00eddo hablar de este hecho en alg\u00fan momento, pero muchos de ellos no saben por qu\u00e9 menos es mejor.<\/p>\n<p>A menudo recibo esta pregunta por correo electr\u00f3nico, donde los jugadores observan que la proporci\u00f3n de cada rango de cartas es la misma tanto si el casino utiliza una sola baraja como si baraja seis barajas juntas.  Independientemente del n\u00famero de barajas en juego, una decimotercera parte de las cartas son ases...<!--more--><\/p>\n<h2 style=\"text-align: center;\">Se consiguen m\u00e1s Blackjacks en partidas con menos barajas<\/h2>\n<p>A pesar de que las proporciones iniciales de cartas son iguales, en los juegos con menos barajas se le repartir\u00e1n m\u00e1s blackjacks.  Tambi\u00e9n tendr\u00e1 m\u00e1s \u00e9xito en sus dobles.  \u00bfC\u00f3mo puede ser eso, cuando todos los rangos est\u00e1n igualmente representados sin importar cu\u00e1ntas barajas se utilicen?  Es porque quitar cartas tiene m\u00e1s impacto en un juego con menos barajas.<\/p>\n<h2 style=\"text-align: center;\">\u00bfCon qu\u00e9 frecuencia sacar\u00e1 un Blackjack de una sola baraja?<\/h2>\n<p>Para obtener la probabilidad de sacar un Blackjack de una sola baraja, multiplicamos la probabilidad de sacar un As por la probabilidad de sacar una carta de valor diez.  En una sola baraja de 52 cartas hay 4 ases y 16 cartas de valor diez (4 de cada diez, jota, reina y rey).<\/p>\n<p>p(As) = 4\/52 = 1\/13<br \/>\np(Diez) = 16\/51<\/p>\n<p>Observe que la segunda l\u00ednea reduce el n\u00famero de cartas del divisor a 51, para tener en cuenta el As eliminado.  Y ah\u00ed es donde radica la diferencia.<\/p>\n<p>Tambi\u00e9n tenemos que doblar el resultado ya que podr\u00edamos sacar (As,Diez) o (Diez,As).  Nuestro resultado final es:<br \/>\np(Blackjack) = p(As) * p(Diez) * 2 = (1\/13) * (16\/51) * 2 = 4,83%<\/p>\n<p><strong>La probabilidad de sacar un blackjack de una sola baraja es de 4,83%.<\/strong><\/p>\n<h2 style=\"text-align: center;\">\u00bfCon qu\u00e9 frecuencia sacar\u00e1 un Blackjack de dos barajas?<\/h2>\n<p>La misma idea con dos barajas, con n\u00fameros diferentes.   104 cartas en total, incluyendo 8 ases y 32 cartas de valor diez...<\/p>\n<p>p(Blackjack) = 8\/104 * 32\/103 * 2 = 4,78%.<\/p>\n<p><strong>La probabilidad de sacar un blackjack de dos barajas es de 4,78%.<\/strong><\/p>\n<p>M\u00e1s barajas significan algo menos de blackjacks.  Con seis barajas, la probabilidad desciende a\u00fan m\u00e1s, hasta 4,75%.<\/p>\n<h2 style=\"text-align: center;\">Los dobles tambi\u00e9n funcionan mejor con menos mazos<\/h2>\n<p>El mismo efecto afecta a los doblajes.  Si doblas tu mano inicial de (6,5) para un total de 11, entonces es ligeramente m\u00e1s probable que saques una carta con la cara para hacer 21 si el juego utiliza menos barajas.<\/p>\n<p>Los lectores m\u00e1s avispados se dar\u00e1n cuenta de que el crupier tambi\u00e9n se beneficia de estos cambios.  As\u00ed es, el crupier obtiene m\u00e1s blackjacks en una sola baraja y saca 21 m\u00e1s a menudo, igual que el jugador.  Pero ten en cuenta que el jugador gana 3:2 por blackjack, mientras que el crupier s\u00f3lo consigue dinero parejo.  Y en manos como la del ejemplo del double down, el jugador gana el doble de la apuesta inicial.  As\u00ed que, aunque tanto el jugador como la banca consiguen m\u00e1s manos buenas, el jugador recibe una recompensa mayor por las suyas.<\/p>\n<h2 style=\"text-align: center;\">\u00a1Pero consigues menos Pat 20 en menos barajas!<\/h2>\n<p>No todo son buenas noticias con menos barajas.  Por la misma raz\u00f3n, \u00a1tendr\u00e1 menos manos repartidas de 20!  Una vez eliminada la primera carta con valor de diez, s\u00f3lo quedan 15 dieces de 51 cartas en la baraja sencilla, mientras que en la baraja doble sus posibilidades son mejores con 31 de 103.<\/p>\n<p>Este impacto de menos pat 20 afecta por igual a los jugadores y a los crupieres, por lo que en realidad es un lavado de cara.<\/p>\n<p>La conclusi\u00f3n es que, en igualdad de condiciones, deber\u00eda jugar en juegos con menos barajas.  Eso s\u00ed, \u00a1aseg\u00farate de que paguen 3:2 en el blackjack!<\/p>","protected":false},"excerpt":{"rendered":"<p>Fewer Decks are Better. Do You Know Why? When it comes to the number of decks in a blackjack game, the fewer the better. Most players have heard this fact somewhere along the line, but many of them don&#8217;t know why fewer is better. I often get this question by email, where players will note [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,3],"tags":[],"class_list":["post-1611","post","type-post","status-publish","format-standard","hentry","category-beginner-articles","category-blackjack"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Why Does The Number of Decks Matter in Blackjack?<\/title>\n<meta name=\"description\" content=\"A common question among new blackjack players is &quot;Why should the number of decks matter?&quot; After all, the ratio of all the card ranks is the same, right?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/es\/por-que-importa-el-numero-de-barajas-en-el-blackjack\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Why Does The Number of Decks Matter in Blackjack?\" \/>\n<meta property=\"og:description\" content=\"A common question among new blackjack players is &quot;Why should the number of decks matter?&quot; After all, the ratio of all the card ranks is the same, right?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/es\/por-que-importa-el-numero-de-barajas-en-el-blackjack\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-16T03:12:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-31T00:14:50+00:00\" \/>\n<meta name=\"author\" content=\"Ken Smith\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/\",\"name\":\"Why Does The Number of Decks Matter in Blackjack?\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2015-09-16T03:12:46+00:00\",\"dateModified\":\"2016-01-31T00:14:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\"},\"description\":\"A common question among new blackjack players is \\\"Why should the number of decks matter?\\\" After all, the ratio of all the card ranks is the same, right?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Why Does The Number of Decks Matter in Blackjack?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\",\"name\":\"Ken Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"caption\":\"Ken Smith\"},\"description\":\"Creator of Blackjackinfo.com, very few can rival Ken's experience and knowledge of blackjack. His blackjack resume includes winning numerous tournament winnings, making several TV appearances and authoring multiple books on blackjack tournament strategy. Discover more about Ken's background and how he got started here\",\"sameAs\":[\"http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/\",\"https:\/\/x.com\/PlayInJersey\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 es importante el n\u00famero de barajas en el Blackjack?","description":"Una pregunta habitual entre los nuevos jugadores de blackjack es \"\u00bfPor qu\u00e9 deber\u00eda importar el n\u00famero de barajas?\". Despu\u00e9s de todo, la proporci\u00f3n de todos los rangos de cartas es la misma, \u00bfverdad?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/es\/por-que-importa-el-numero-de-barajas-en-el-blackjack\/","og_locale":"es_ES","og_type":"article","og_title":"Why Does The Number of Decks Matter in Blackjack?","og_description":"A common question among new blackjack players is \"Why should the number of decks matter?\" After all, the ratio of all the card ranks is the same, right?","og_url":"https:\/\/www.blackjackinfo.com\/es\/por-que-importa-el-numero-de-barajas-en-el-blackjack\/","og_site_name":"BlackjackInfo.com","article_published_time":"2015-09-16T03:12:46+00:00","article_modified_time":"2016-01-31T00:14:50+00:00","author":"Ken Smith","twitter_misc":{"Escrito por":"Ken Smith","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/","url":"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/","name":"\u00bfPor qu\u00e9 es importante el n\u00famero de barajas en el Blackjack?","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2015-09-16T03:12:46+00:00","dateModified":"2016-01-31T00:14:50+00:00","author":{"@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71"},"description":"Una pregunta habitual entre los nuevos jugadores de blackjack es \"\u00bfPor qu\u00e9 deber\u00eda importar el n\u00famero de barajas?\". Despu\u00e9s de todo, la proporci\u00f3n de todos los rangos de cartas es la misma, \u00bfverdad?","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/why-does-the-number-of-decks-matter-in-blackjack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"Why Does The Number of Decks Matter in Blackjack?"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"\u00a1Porque ganar es m\u00e1s divertido!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71","name":"Ken Smith","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","caption":"Ken Smith"},"description":"Creador de Blackjackinfo.com, muy pocos pueden rivalizar con la experiencia y los conocimientos de Ken sobre el blackjack. Su curr\u00edculum en el blackjack incluye numerosas victorias en torneos, varias apariciones en televisi\u00f3n y la autor\u00eda de m\u00faltiples libros sobre estrategia en torneos de blackjack. Descubra m\u00e1s sobre la trayectoria de Ken y c\u00f3mo empez\u00f3 aqu\u00ed","sameAs":["http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/","https:\/\/x.com\/PlayInJersey"]}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/posts\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/comments?post=1611"}],"version-history":[{"count":15,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/posts\/1611\/revisions"}],"predecessor-version":[{"id":1663,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/posts\/1611\/revisions\/1663"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/categories?post=1611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/es\/wp-json\/wp\/v2\/tags?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}