{"id":106,"date":"2012-10-11T22:18:57","date_gmt":"2012-10-12T03:18:57","guid":{"rendered":"http:\/\/www.blackjackinfo.com\/blog\/?p=106"},"modified":"2014-12-21T21:58:31","modified_gmt":"2014-12-22T02:58:31","slug":"a-quel-point-loeil-dans-le-ciel-est-il-intelligent","status":"publish","type":"post","link":"https:\/\/www.blackjackinfo.com\/fr\/just-how-smart-is-the-eye-in-the-sky\/","title":{"rendered":"Quelle est l'intelligence de l'\u0153il dans le ciel ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-108\" title=\"Security Camera\" src=\"\/files\/Security-camera.jpg\" alt=\"Security Camera\" width=\"300\" height=\"188\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"intro\">Si vous \u00eates un joueur de blackjack exp\u00e9riment\u00e9, vous savez tr\u00e8s bien qu'un op\u00e9rateur de surveillance peut surveiller votre jeu \u00e0 tout moment, gr\u00e2ce au r\u00e9seau de cam\u00e9ras qui pars\u00e8ment le plafond de tous les casinos.  Mais saviez-vous qu'un ordinateur pouvait vous surveiller \u00e0 la place ?<\/p>\n<p>Gr\u00e2ce \u00e0 la technologie d\u00e9j\u00e0 utilis\u00e9e dans l'industrie des casinos, votre jeu peut \u00eatre analys\u00e9 automatiquement sans intervention humaine.<br \/>\n<!--more--><br \/>\nLa semaine derni\u00e8re, j'\u00e9tais \u00e0 Las Vegas pour l'exposition annuelle Global Gaming Expo. Le G2E est le plus grand salon professionnel consacr\u00e9 \u00e0 l'industrie du jeu, et la conf\u00e9rence propose des sessions avec des intervenants dans de nombreux domaines d'expertise. Bien que la conf\u00e9rence soit destin\u00e9e aux initi\u00e9s du secteur, il m'arrive de payer pour y assister afin d'avoir une id\u00e9e pr\u00e9cise de ce qui se passe de l'autre c\u00f4t\u00e9 du jeu.<\/p>\n<p>L'une des sessions les plus int\u00e9ressantes \u00e9tait <em>\"Technologie des jeux de table : Les choix et les options\"<\/em>. Le mod\u00e9rateur de la session \u00e9tait un vieil ami \u00e0 moi, Max Rubin. Max \u00e9tait l'un des experts commentateurs de l'Ultimate Blackjack Tour, \u00e0 l'\u00e9poque o\u00f9 je participais \u00e0 cette s\u00e9rie d'\u00e9missions t\u00e9l\u00e9vis\u00e9es sur CBS. Je me suis gliss\u00e9 dans la salle quelques minutes apr\u00e8s le d\u00e9but de la session et j'ai pris place \u00e0 l'arri\u00e8re. Comme d'habitude, j'\u00e9tais probablement la seule personne pr\u00e9sente qui n'\u00e9tait pas un employ\u00e9 du casino. Je regarde toujours autour de moi nerveusement, en esp\u00e9rant que personne ne me remarque !<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #008000;\">Big Brother est d\u00e9j\u00e0 l\u00e0<\/span><\/h2>\n<p style=\"text-align: left;\">Apr\u00e8s une discussion avec les pan\u00e9listes sur les diff\u00e9rentes technologies, Max a fait quelques commentaires que j'ai trouv\u00e9s tr\u00e8s int\u00e9ressants. Rubin est consultant en jeux de table pour le casino Barona, pr\u00e8s de San Diego. Au cours de la session, il a fait remarquer que Barona <strong>a mis en place un syst\u00e8me de suivi<\/strong> sur leurs jeux \u00e0 deux \u00e9tages. En utilisant le flux vid\u00e9o des cam\u00e9ras, le syst\u00e8me peut d\u00e9terminer si un joueur utilise le double-deck. <span style=\"color: #333399;\"><strong>strat\u00e9gie de base<\/strong><\/span>qu'un joueur soit <span style=\"color: #333399;\"><strong>comptage des cartes<\/strong><\/span>et si le joueur utilise <span style=\"color: #333399;\"><strong>num\u00e9ros d'index<\/strong><\/span> pour modifier les d\u00e9cisions strat\u00e9giques. Le logiciel peut \u00e9galement d\u00e9tecter <span style=\"color: #333399;\"><strong>carte \u00e0 trous<\/strong><\/span> des pi\u00e8ces de th\u00e9\u00e2tre, et <span style=\"color: #333399;\"><strong>carte suivante<\/strong><\/span> joue.<\/p>\n<p>Le produit auquel Max fait r\u00e9f\u00e9rence est TableEye21, et il a \u00e9t\u00e9 d\u00e9velopp\u00e9 par l'un des pan\u00e9listes de la session.  Prem Gururajan est le PDG d'une soci\u00e9t\u00e9 canadienne appel\u00e9e <a title=\"Tangam Gaming\" href=\"http:\/\/www.tangamgaming.com\">Syst\u00e8mes Tangam<\/a>qui produit ce logiciel et plusieurs autres pour la gestion des jeux de table.  L'installation \u00e0 Barona remonte au moins \u00e0 2010, lorsque Gururajan l'a mentionn\u00e9e dans un article du magazine Popular Mechanics.  (L'article est <a title=\"Article du casino Popular Mechanics\" href=\"http:\/\/www.popularmechanics.com\/technology\/how-to\/computer-security\/4341499?\"> disponible en ligne<\/a>.)  Le fait que le syst\u00e8me soit toujours en place plus de deux ans apr\u00e8s signifie qu'il apporte de la valeur \u00e0 Barona, et je m'attends \u00e0 ce qu'il fasse bient\u00f4t surface dans d'autres propri\u00e9t\u00e9s.<\/p>\n<p>M\u00eame avec toutes ces preuves que le syst\u00e8me fonctionne dans un environnement de casino en direct, je remarque que TableEye21 n'est PAS mentionn\u00e9 dans la liste normale des produits sur le site Web de Tangam.  Ils pr\u00e9sentent un produit similaire appel\u00e9 TableEyeBacc pour les jeux de baccarat, ce qui me fait penser que le produit pour le blackjack doit encore avoir quelques d\u00e9fauts.  Quoi qu'il en soit, il s'agit d'une preuve de concept impressionnante et je pense que si le prix est correct, de nombreux casinos sauteront sur l'occasion d'installer ce produit.  Comme nous ne le savons que trop bien, la plupart des casinos sont pr\u00eats \u00e0 d\u00e9penser des sommes ridicules pour se prot\u00e9ger contre la menace relativement faible des joueurs d'avantage.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-109\" title=\"Digital Surveillance\" src=\"\/files\/Digital-Security.jpg\" alt=\"Digital Surveillance\" width=\"300\" height=\"225\" data-no-auto-translation=\"\" \/><\/p>\n<p>Que doit donc faire un joueur exp\u00e9riment\u00e9 ?  Les conseils habituels restent valables :  Limitez la dur\u00e9e de vos sessions.  Changez de table.  Jouez de mani\u00e8re anonyme.  R\u00e9partissez votre jeu sur plusieurs \u00e9quipes afin que le m\u00eame personnel de la fosse ne vous voie pas \u00e0 plusieurs reprises.  \u00c9vitez les heures de changement d'\u00e9quipe.<\/p>\n<p>Ne vous inqui\u00e9tez pas.  Notre jeu pr\u00e9f\u00e9r\u00e9 n'est pas en voie de disparition.  Avec l'explosion des tables de blackjack dans toutes les r\u00e9gions du pays, vous pouvez encore trouver un tr\u00e8s bon jeu dans la plupart des r\u00e9gions.  Les rumeurs sur la disparition du blackjack battable courent depuis que je joue \u00e0 ce jeu.  Toutes ces avanc\u00e9es technologiques en mati\u00e8re de protection du jeu sont certainement pr\u00e9occupantes, mais elles ne tueront pas le jeu.  Je vous le garantis.<\/p>\n<p>TableEye n'est que l'une des nombreuses technologies int\u00e9ressantes qui ont \u00e9t\u00e9 abord\u00e9es au cours de cette session. Je parlerai des puces RFID dans mon prochain article. Restez \u00e0 l'\u00e9coute. Vous pouvez vous abonner aux articles du blog gr\u00e2ce \u00e0 notre <a title=\"Flux RSS du blog BlackjackInfo\" href=\"\/feed\/\">Flux RSS<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cet impressionnant syst\u00e8me de reconnaissance visuelle automatis\u00e9 peut regarder des s\u00e9quences de vid\u00e9osurveillance et d\u00e9terminer \u00e0 quel point vous \u00eates un bon joueur de blackjack.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-106","post","type-post","status-publish","format-standard","hentry","category-blackjack","category-card-counting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Just How Smart is the Eye in the Sky?<\/title>\n<meta name=\"description\" content=\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/fr\/a-quel-point-loeil-dans-le-ciel-est-il-intelligent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Just How Smart is the Eye in the Sky?\" \/>\n<meta property=\"og:description\" content=\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/fr\/a-quel-point-loeil-dans-le-ciel-est-il-intelligent\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-12T03:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-22T02:58:31+00:00\" \/>\n<meta name=\"author\" content=\"Ken Smith\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\",\"name\":\"Just How Smart is the Eye in the Sky?\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2012-10-12T03:18:57+00:00\",\"dateModified\":\"2014-12-22T02:58:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\"},\"description\":\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Just How Smart is the Eye in the Sky?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\",\"name\":\"Ken Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"caption\":\"Ken Smith\"},\"description\":\"Creator of Blackjackinfo.com, very few can rival Ken's experience and knowledge of blackjack. His blackjack resume includes winning numerous tournament winnings, making several TV appearances and authoring multiple books on blackjack tournament strategy. Discover more about Ken's background and how he got started here\",\"sameAs\":[\"http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/\",\"https:\/\/x.com\/PlayInJersey\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle est l'intelligence de l'\u0153il dans le ciel ?","description":"Cet impressionnant syst\u00e8me de reconnaissance visuelle automatis\u00e9 peut regarder des s\u00e9quences de vid\u00e9osurveillance et d\u00e9terminer \u00e0 quel point vous \u00eates un bon joueur de blackjack.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/fr\/a-quel-point-loeil-dans-le-ciel-est-il-intelligent\/","og_locale":"fr_FR","og_type":"article","og_title":"Just How Smart is the Eye in the Sky?","og_description":"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.","og_url":"https:\/\/www.blackjackinfo.com\/fr\/a-quel-point-loeil-dans-le-ciel-est-il-intelligent\/","og_site_name":"BlackjackInfo.com","article_published_time":"2012-10-12T03:18:57+00:00","article_modified_time":"2014-12-22T02:58:31+00:00","author":"Ken Smith","twitter_misc":{"\u00c9crit par":"Ken Smith","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/","url":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/","name":"Quelle est l'intelligence de l'\u0153il dans le ciel ?","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2012-10-12T03:18:57+00:00","dateModified":"2014-12-22T02:58:31+00:00","author":{"@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71"},"description":"Cet impressionnant syst\u00e8me de reconnaissance visuelle automatis\u00e9 peut regarder des s\u00e9quences de vid\u00e9osurveillance et d\u00e9terminer \u00e0 quel point vous \u00eates un bon joueur de blackjack.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"Just How Smart is the Eye in the Sky?"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"Parce que gagner, c'est plus amusant !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71","name":"Ken Smith","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","caption":"Ken Smith"},"description":"Cr\u00e9ateur de Blackjackinfo.com, peu de gens peuvent rivaliser avec l'exp\u00e9rience et les connaissances de Ken en mati\u00e8re de blackjack. Son curriculum vitae dans le domaine du blackjack comprend de nombreuses victoires dans des tournois, plusieurs apparitions \u00e0 la t\u00e9l\u00e9vision et la r\u00e9daction de plusieurs livres sur la strat\u00e9gie des tournois de blackjack. Pour en savoir plus sur le parcours de Ken et sur ses d\u00e9buts, cliquez ici.","sameAs":["http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/","https:\/\/x.com\/PlayInJersey"]}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":38,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"predecessor-version":[{"id":1012,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/posts\/106\/revisions\/1012"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/fr\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}