{"id":106,"date":"2012-10-11T22:18:57","date_gmt":"2012-10-12T03:18:57","guid":{"rendered":"http:\/\/www.blackjackinfo.com\/blog\/?p=106"},"modified":"2014-12-21T21:58:31","modified_gmt":"2014-12-22T02:58:31","slug":"quanto-e-intelligente-locchio-nel-cielo","status":"publish","type":"post","link":"https:\/\/www.blackjackinfo.com\/it\/just-how-smart-is-the-eye-in-the-sky\/","title":{"rendered":"Quanto \u00e8 intelligente l'occhio nel cielo?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-108\" title=\"Security Camera\" src=\"\/files\/Security-camera.jpg\" alt=\"Security Camera\" width=\"300\" height=\"188\" data-no-auto-translation=\"\" \/><\/p>\n<p class=\"intro\">Se siete abili giocatori di blackjack, sapete bene che un operatore di sorveglianza potrebbe osservare le vostre giocate in qualsiasi momento, grazie alla rete di telecamere che punteggiano il soffitto di ogni casin\u00f2.  Ma sapevate che invece un computer potrebbe osservarvi?<\/p>\n<p>Grazie alla tecnologia gi\u00e0 in uso nel settore dei casin\u00f2, le giocate possono essere analizzate automaticamente senza l'intervento umano.<br \/>\n<!--more--><br \/>\nLa scorsa settimana sono stato a Las Vegas per l'annuale Global Gaming Expo. Il G2E \u00e8 la pi\u00f9 grande fiera dedicata all'industria del gioco d'azzardo e la conferenza prevede sessioni con relatori in molte aree di competenza. Sebbene la conferenza sia destinata agli addetti ai lavori, di tanto in tanto pago per partecipare alla conferenza per avere un'idea precisa di ci\u00f2 che accade dall'altra parte del gioco.<\/p>\n<p>Una delle sessioni pi\u00f9 interessanti \u00e8 stata <em>\"Tecnologia dei giochi da tavolo: Le scelte e le opzioni\".<\/em>. Il moderatore della sessione era un mio vecchio amico, Max Rubin. Max era uno degli esperti commentatori dell'Ultimate Blackjack Tour, quando partecipavo a quella serie di spettacoli televisivi sulla CBS. Mi sono intrufolato nella sessione pochi minuti dopo l'inizio e ho preso posto vicino al fondo. Come al solito, ero probabilmente l'unica persona presente che non fosse un dipendente del casin\u00f2. Mi guardo sempre intorno nervosamente, sperando che nessuno mi noti!<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #008000;\">Il Grande Fratello \u00e8 gi\u00e0 qui<\/span><\/h2>\n<p style=\"text-align: left;\">Dopo alcune discussioni con i relatori sulle varie tecnologie, Max ha fatto alcuni commenti che ho trovato molto interessanti. Rubin \u00e8 un consulente per i giochi da tavolo del Casin\u00f2 Barona, vicino a San Diego. Durante la sessione, ha notato che Barona <strong>ha un sistema di tracciamento in atto<\/strong> sulle loro partite a doppio mazzo. Utilizzando il feed video delle telecamere, il sistema \u00e8 in grado di valutare se un giocatore sta usando <span style=\"color: #333399;\"><strong>strategia di base<\/strong><\/span>, se un giocatore \u00e8 <span style=\"color: #333399;\"><strong>conteggio delle carte<\/strong><\/span>e se il giocatore sta usando <span style=\"color: #333399;\"><strong>numeri indice<\/strong><\/span> per modificare le decisioni strategiche. Il software pu\u00f2 anche rilevare <span style=\"color: #333399;\"><strong>carta a buchi<\/strong><\/span> e <span style=\"color: #333399;\"><strong>scheda successiva<\/strong><\/span> gioca.<\/p>\n<p>Il prodotto a cui Max si riferisce \u00e8 TableEye21 ed \u00e8 stato sviluppato da uno dei relatori della sessione.  Prem Gururajan \u00e8 l'amministratore delegato di un'azienda canadese chiamata <a title=\"Gioco d&#039;azzardo Tangam\" href=\"http:\/\/www.tangamgaming.com\">Sistemi Tangam<\/a>che produce questo e molti altri prodotti software per la gestione dei giochi da tavolo.  L'installazione alla Barona risale almeno al 2010, quando \u00e8 stata menzionata da Gururajan in un articolo della rivista Popular Mechanics.  (L'articolo \u00e8 <a title=\"Articolo sul casin\u00f2 di Popular Mechanics\" href=\"http:\/\/www.popularmechanics.com\/technology\/how-to\/computer-security\/4341499?\"> disponibile online<\/a>.)  Il fatto che il sistema sia ancora in vigore a distanza di oltre 2 anni significa che sta fornendo un valore aggiunto a Barona e mi aspetto che presto venga utilizzato anche in altre propriet\u00e0.<\/p>\n<p>Anche con tutte queste prove che il sistema funziona in un ambiente di casin\u00f2 dal vivo, ho notato che TableEye21 NON \u00e8 menzionato nel normale elenco dei prodotti sul sito web di Tangam.  Il sito presenta un prodotto simile, TableEyeBacc, per i giochi di baccarat, il che mi fa pensare che il prodotto per il blackjack debba avere ancora qualche problema.  Ad ogni modo, si tratta di una prova di concetto impressionante e credo che, se il prezzo \u00e8 giusto, molti casin\u00f2 coglieranno al volo l'opportunit\u00e0 di installare questo prodotto.  Come sappiamo fin troppo bene, la maggior parte dei casin\u00f2 \u00e8 disposta a spendere cifre ridicole per proteggersi dalla minaccia relativamente piccola dei giocatori in vantaggio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-109\" title=\"Digital Surveillance\" src=\"\/files\/Digital-Security.jpg\" alt=\"Digital Surveillance\" width=\"300\" height=\"225\" data-no-auto-translation=\"\" \/><\/p>\n<p>Quindi, cosa deve fare un giocatore esperto?  I soliti consigli sono sempre validi:  Mantenere le sessioni brevi.  Cambiare tavolo.  Giocare in modo anonimo.  Distribuite le vostre giocate su diversi turni, in modo che il personale di sala non vi veda ripetutamente.  Evitate gli orari di cambio turno.<\/p>\n<p>Non preoccupatevi.  Il nostro gioco preferito non sta andando da nessuna parte.  Con l'esplosione dei tavoli da blackjack in ogni parte del Paese, \u00e8 ancora possibile trovare un ottimo gioco nella maggior parte delle aree.  Le voci sulla scomparsa del blackjack con la possibilit\u00e0 di battere sono state diffuse da quando gioco.  Tutti questi progressi tecnologici nella protezione del gioco sono certamente preoccupanti, ma non uccideranno il gioco.  Ve lo garantisco.<\/p>\n<p>TableEye \u00e8 stata solo una delle numerose tecnologie interessanti discusse durante questa sessione. Nel prossimo post parler\u00f2 dei chip RFID. Restate sintonizzati. Potete abbonarvi ai post del blog con il nostro <a title=\"Feed RSS del blog BlackjackInfo\" href=\"\/feed\/\">Feed RSS<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Questo impressionante sistema di riconoscimento visivo automatizzato \u00e8 in grado di guardare i filmati di videosorveglianza e di determinare quanto siete abili giocatori di blackjack.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-106","post","type-post","status-publish","format-standard","hentry","category-blackjack","category-card-counting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Just How Smart is the Eye in the Sky?<\/title>\n<meta name=\"description\" content=\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/it\/quanto-e-intelligente-locchio-nel-cielo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Just How Smart is the Eye in the Sky?\" \/>\n<meta property=\"og:description\" content=\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/it\/quanto-e-intelligente-locchio-nel-cielo\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-12T03:18:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-22T02:58:31+00:00\" \/>\n<meta name=\"author\" content=\"Ken Smith\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\",\"name\":\"Just How Smart is the Eye in the Sky?\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2012-10-12T03:18:57+00:00\",\"dateModified\":\"2014-12-22T02:58:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\"},\"description\":\"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Just How Smart is the Eye in the Sky?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\",\"name\":\"Ken Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"caption\":\"Ken Smith\"},\"description\":\"Creator of Blackjackinfo.com, very few can rival Ken's experience and knowledge of blackjack. His blackjack resume includes winning numerous tournament winnings, making several TV appearances and authoring multiple books on blackjack tournament strategy. Discover more about Ken's background and how he got started here\",\"sameAs\":[\"http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/\",\"https:\/\/x.com\/PlayInJersey\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quanto \u00e8 intelligente l'occhio nel cielo?","description":"Questo impressionante sistema di riconoscimento visivo automatizzato \u00e8 in grado di guardare i filmati di videosorveglianza e di determinare quanto siete abili giocatori di blackjack.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/it\/quanto-e-intelligente-locchio-nel-cielo\/","og_locale":"it_IT","og_type":"article","og_title":"Just How Smart is the Eye in the Sky?","og_description":"This impressive automated visual recognition system can watch video surveillance footage and determine how skilled a blackjack player you are.","og_url":"https:\/\/www.blackjackinfo.com\/it\/quanto-e-intelligente-locchio-nel-cielo\/","og_site_name":"BlackjackInfo.com","article_published_time":"2012-10-12T03:18:57+00:00","article_modified_time":"2014-12-22T02:58:31+00:00","author":"Ken Smith","twitter_misc":{"Scritto da":"Ken Smith","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/","url":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/","name":"Quanto \u00e8 intelligente l'occhio nel cielo?","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2012-10-12T03:18:57+00:00","dateModified":"2014-12-22T02:58:31+00:00","author":{"@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71"},"description":"Questo impressionante sistema di riconoscimento visivo automatizzato \u00e8 in grado di guardare i filmati di videosorveglianza e di determinare quanto siete abili giocatori di blackjack.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/just-how-smart-is-the-eye-in-the-sky\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"Just How Smart is the Eye in the Sky?"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"Perch\u00e9 vincere \u00e8 pi\u00f9 divertente!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71","name":"Ken Smith","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","caption":"Ken Smith"},"description":"Creatore di Blackjackinfo.com, pochi possono competere con l'esperienza e la conoscenza del blackjack di Ken. Il suo curriculum nel blackjack comprende numerose vincite nei tornei, diverse apparizioni televisive e la stesura di diversi libri sulla strategia dei tornei di blackjack. Scoprite di pi\u00f9 sul background di Ken e su come ha iniziato qui","sameAs":["http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/","https:\/\/x.com\/PlayInJersey"]}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":38,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"predecessor-version":[{"id":1012,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/106\/revisions\/1012"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}