{"id":45,"date":"2006-02-15T10:22:00","date_gmt":"2006-02-15T15:22:00","guid":{"rendered":"http:\/\/www.blackjackinfo.com\/blog\/2006\/02\/wsob-waiting-game\/"},"modified":"2014-12-21T22:09:55","modified_gmt":"2014-12-22T03:09:55","slug":"gioco-dattesa-wsob","status":"publish","type":"post","link":"https:\/\/www.blackjackinfo.com\/it\/wsob-waiting-game\/","title":{"rendered":"WSOB Gioco d'attesa"},"content":{"rendered":"<p>Questa \u00e8 la settimana.  Molti giocatori guardano con ansia il telefono questa settimana sperando in una telefonata da parte di GSN's World Series of Blackjack.  La stagione 2006 dello show televisivo inizier\u00e0 le riprese tra meno di due settimane e ci sono ancora posti da assegnare.<br \/>\n<!--more--><\/p>\n<p>Anche se i numeri ufficiali non sono stati rilasciati da GSN, sembra che dei 40 posti riservati ai giocatori nell'evento televisivo, solo 20-30 siano stati occupati dai qualificati via satellite.  Restano quindi tra i 10 e i 20 posti da assegnare da parte di GSN.  Per questo motivo, molti giocatori hanno inviato le loro credenziali per il torneo ai produttori, sperando di poter partecipare a un freeroll e di poter vincere il primo premio del $500.000.<\/p>\n<p>Dopo aver inviato le informazioni iniziali, a molti giocatori \u00e8 stato chiesto di fornire un breve video di loro stessi.  Negli ultimi giorni, alcuni potenziali partecipanti hanno ricevuto telefonate di follow-up con domande aggiuntive.  Mi aspetto che le decisioni vengano prese entro la fine di questa settimana.<\/p>\n<p>Quella telefonata vale ben $25.000 di valore atteso.  Squillo, squillo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Questa \u00e8 la settimana. Molti giocatori guardano con ansia il telefono questa settimana sperando in una telefonata da parte di GSN's World Series of Blackjack. La stagione 2006 dello show televisivo inizier\u00e0 le riprese tra meno di due settimane e ci sono ancora posti da assegnare.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-45","post","type-post","status-publish","format-standard","hentry","category-blackjack-tournaments"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WSOB Waiting game<\/title>\n<meta name=\"description\" content=\"Many well-known players are anxiously waiting by the phone, hoping to be invited to participate in the next season of World Series of Blackjack.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/it\/gioco-dattesa-wsob\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WSOB Waiting game\" \/>\n<meta property=\"og:description\" content=\"Many well-known players are anxiously waiting by the phone, hoping to be invited to participate in the next season of World Series of Blackjack.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/it\/gioco-dattesa-wsob\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:published_time\" content=\"2006-02-15T15:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-22T03:09:55+00:00\" \/>\n<meta name=\"author\" content=\"Ken Smith\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ken Smith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/\",\"name\":\"WSOB Waiting game\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2006-02-15T15:22:00+00:00\",\"dateModified\":\"2014-12-22T03:09:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\"},\"description\":\"Many well-known players are anxiously waiting by the phone, hoping to be invited to participate in the next season of World Series of Blackjack.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WSOB Waiting game\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71\",\"name\":\"Ken Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg\",\"caption\":\"Ken Smith\"},\"description\":\"Creator of Blackjackinfo.com, very few can rival Ken's experience and knowledge of blackjack. His blackjack resume includes winning numerous tournament winnings, making several TV appearances and authoring multiple books on blackjack tournament strategy. Discover more about Ken's background and how he got started here\",\"sameAs\":[\"http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/\",\"https:\/\/x.com\/PlayInJersey\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WSOB Gioco d'attesa","description":"Molti giocatori famosi aspettano con ansia il telefono, sperando di essere invitati a partecipare alla prossima stagione delle World Series of Blackjack.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/it\/gioco-dattesa-wsob\/","og_locale":"it_IT","og_type":"article","og_title":"WSOB Waiting game","og_description":"Many well-known players are anxiously waiting by the phone, hoping to be invited to participate in the next season of World Series of Blackjack.","og_url":"https:\/\/www.blackjackinfo.com\/it\/gioco-dattesa-wsob\/","og_site_name":"BlackjackInfo.com","article_published_time":"2006-02-15T15:22:00+00:00","article_modified_time":"2014-12-22T03:09:55+00:00","author":"Ken Smith","twitter_misc":{"Scritto da":"Ken Smith","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/","url":"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/","name":"WSOB Gioco d'attesa","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2006-02-15T15:22:00+00:00","dateModified":"2014-12-22T03:09:55+00:00","author":{"@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71"},"description":"Molti giocatori famosi aspettano con ansia il telefono, sperando di essere invitati a partecipare alla prossima stagione delle World Series of Blackjack.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/wsob-waiting-game\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"WSOB Waiting game"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"Perch\u00e9 vincere \u00e8 pi\u00f9 divertente!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/31c2cd18f9204497aa4ea15677d81f71","name":"Ken Smith","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.blackjackinfo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aeda1362e181721ba668049cbbe76187053b6bbb4e973d90f8378b0ee68c40c?s=96&d=https%3A%2F%2Fwww.blackjackinfo.com%2Ffiles%2Fchip-1.png&r=pg","caption":"Ken Smith"},"description":"Creatore di Blackjackinfo.com, pochi possono competere con l'esperienza e la conoscenza del blackjack di Ken. Il suo curriculum nel blackjack comprende numerose vincite nei tornei, diverse apparizioni televisive e la stesura di diversi libri sulla strategia dei tornei di blackjack. Scoprite di pi\u00f9 sul background di Ken e su come ha iniziato qui","sameAs":["http:\/\/www.sweet-tea-no-lemon.com\/ken-smith\/","https:\/\/x.com\/PlayInJersey"]}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":1,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"predecessor-version":[{"id":989,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/posts\/45\/revisions\/989"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/it\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}