{"id":1499,"date":"2014-12-22T23:06:06","date_gmt":"2014-12-23T05:06:06","guid":{"rendered":"https:\/\/test.blackjackinfo.com\/?page_id=1499"},"modified":"2018-06-22T02:44:46","modified_gmt":"2018-06-22T07:44:46","slug":"%e0%b8%aa%e0%b8%b4%e0%b8%9a%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%9c%e0%b8%b4%e0%b8%94%e0%b8%9e%e0%b8%a5%e0%b8%b2%e0%b8%94%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%90%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%a5","status":"publish","type":"page","link":"https:\/\/www.blackjackinfo.com\/th\/top-ten-blackjack-basic-strategy-mistakes\/","title":{"rendered":"\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04"},"content":{"rendered":"<div class=\"top-ten-mistakes\">\n<p class=\"intro\">\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e41\u0e08\u0e47\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e32\u0e14\u0e40\u0e14\u0e32\u0e44\u0e14\u0e49 \u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e0a\u0e19\u0e30\u0e21\u0e32\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e40\u0e2a\u0e35\u0e22\u0e21\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e04\u0e38\u0e13\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e42\u0e0a\u0e04\u0e14\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e0a\u0e04\u0e23\u0e49\u0e32\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e41\u0e1e\u0e49\u0e2a\u0e38\u0e17\u0e18\u0e34 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e09\u0e25\u0e32\u0e14\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e38\u0e13\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01.<\/p>\n<p>\n\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e41\u0e08\u0e47\u0e01\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e23\u0e27\u0e21 2% \u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07. \u0e2d\u0e32\u0e08\u0e1f\u0e31\u0e07\u0e14\u0e39\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e21\u0e31\u0e19\u0e41\u0e1e\u0e07\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e17\u0e48\u0e32.\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e40\u0e01\u0e21\u0e44\u0e1e\u0e48 6 \u0e2a\u0e33\u0e23\u0e31\u0e1a\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 0.5% \u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e43\u0e19\u0e40\u0e01\u0e21\u0e44\u0e1e\u0e48 2 \u0e2a\u0e33\u0e23\u0e31\u0e1a\u0e41\u0e17\u0e19\u0e08\u0e30\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 0.2% \u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e44\u0e1e\u0e48 1 \u0e2a\u0e33\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e0e\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e08\u0e30\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e17\u0e38\u0e19.\n<\/p>\n<p>\n\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e1e\u0e19\u0e31\u0e19 $10 \u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e44\u0e1e\u0e48 6 \u0e2a\u0e33\u0e23\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e19 Las Vegas Strip \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 $600 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22 2% \u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e2b\u0e23\u0e37\u0e2d $12 \u0e15\u0e48\u0e2d\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22 0.5% \u0e08\u0e32\u0e01 $600 \u0e41\u0e17\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 $3.\n<\/p>\n<p>\n\u0e2d\u0e30\u0e44\u0e23\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49? \u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e41\u0e08\u0e47\u0e01\u0e17\u0e33\u0e01\u0e31\u0e19 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2a\u0e21\u0e21\u0e15\u0e34\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19 $10 \u0e15\u0e48\u0e2d\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e40\u0e01\u0e21 6 \u0e2a\u0e33\u0e23\u0e31\u0e1a \u0e17\u0e35\u0e48\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49 17 \u0e41\u0e15\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e41\u0e22\u0e01\u0e44\u0e1e\u0e48\u0e44\u0e14\u0e49.\n<\/p>\n<p>    <!-- Mistake 10-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">10<\/div>\n<p>12 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d 3<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>HIT<\/div>\n<div class=\"clearfix\"><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e41\u0e15\u0e49\u0e21 12 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e21 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e08\u0e30\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 \u201c\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e44\u0e1e\u0e48\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e49\u201d \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u0e0a\u0e2d\u0e1a\u0e1f\u0e31\u0e07\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e21\u0e32\u0e01.<\/p>\n<p>\u0e42\u0e14\u0e22\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e22\u0e37\u0e19\u0e2a\u0e39\u0e49\u0e01\u0e31\u0e1a 12 \u0e15\u0e48\u0e2d 3 \u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22 $2.55 \u0e01\u0e32\u0e23\u0e42\u0e08\u0e21\u0e15\u0e35\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e04\u0e48\u0e32\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22 $2.31 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e42\u0e08\u0e21\u0e15\u0e35\u0e08\u0e30\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 24 \u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c.<\/p>\n<\/div>\n<\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\"> \u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $2.55<\/div>\n<\/div>\n<div class=\"col-xs-6 col-sm-4\"> \u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $2.31<\/div>\n<\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.24 <span class=\"red\">(\u0e2e\u0e34\u0e15)<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>   <!-- Mistake 9-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">9<\/div>\n<p>        (\u0e40\u0e2d\u0e0b, 7) \u0e1e\u0e1a \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d \u0e2a\u0e34\u0e1a<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>HIT<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e25\u0e48\u0e19\u0e44\u0e1e\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e19\u0e35\u0e49\u0e1c\u0e34\u0e14 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32 \u0e17\u0e33\u0e44\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e35 18 \u0e14\u0e49\u0e27\u0e22\u0e25\u0e48\u0e30? \u0e40\u0e2d\u0e32\u0e25\u0e48\u0e30 \u0e1c\u0e21\u0e08\u0e30\u0e1a\u0e2d\u0e01\u0e04\u0e38\u0e13\u0e27\u0e48\u0e32\u0e17\u0e33\u0e44\u0e21 18 \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1e\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e14\u0e35 \u0e21\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1e\u0e48\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e49\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e22\u0e31\u0e07\u0e44\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e43\u0e0a\u0e48 \u0e04\u0e38\u0e13\u0e21\u0e31\u0e01\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e1e\u0e48\u0e41\u0e22\u0e48\u0e25\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e35 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e44\u0e21\u0e48\u0e42\u0e01\u0e2b\u0e01:<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\"> \u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $1.80<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\"> \u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $1.43<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.37 <span class=\"red\">(\u0e2e\u0e34\u0e15)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 8-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">8<\/div>\n<p>        \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a \u201c\u0e40\u0e07\u0e34\u0e19\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19\u201d \u0e43\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>\u0e2d\u0e22\u0e48\u0e32<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e08\u0e30\u0e1a\u0e2d\u0e01\u0e04\u0e38\u0e13\u0e27\u0e48\u0e32 \u201c\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e43\u0e19\u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u201d \u0e43\u0e0a\u0e48 \u0e21\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22 \u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e40\u0e07\u0e34\u0e19\u0e01\u0e47\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e19\u0e31\u0e1a\u0e44\u0e1e\u0e48 \u0e21\u0e31\u0e19\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e17\u0e35\u0e48\u0e42\u0e07\u0e48\u0e40\u0e02\u0e25\u0e32.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\"> \u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19:<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> $10.00 (\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07)<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\"> \u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e19:<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> $10.39 (\u0e42\u0e14\u0e22\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22)<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.39 <span class=\"red\">(\u0e2d\u0e22\u0e48\u0e32)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 7-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">7<\/div>\n<p>        12 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d 2<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>HIT<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e19\u0e35\u0e48\u0e01\u0e47\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a 12 \u0e15\u0e48\u0e2d 3 \u0e40\u0e25\u0e22 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e41\u0e01\u0e49\u0e15\u0e31\u0e27\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e23\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e22\u0e34\u0e48\u0e07\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e35\u0e01...<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\"> \u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $2.96<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\"> \u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $2.52<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.44 <span class=\"red\">(\u0e2e\u0e34\u0e15)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 6-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">6<\/div>\n<p>        (8,8) \u0e1e\u0e1a \u0e40\u0e17\u0e47\u0e19<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>\u0e41\u0e22\u0e01<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e44\u0e14\u0e49\u0e1a\u0e48\u0e2d\u0e22 \u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a \u0e1f\u0e31\u0e07\u0e14\u0e39\u0e2a\u0e21\u0e40\u0e2b\u0e15\u0e38\u0e2a\u0e21\u0e1c\u0e25\u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21? \u0e41\u0e15\u0e48\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e44\u0e1b \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e2b\u0e32\u0e01\u0e40\u0e23\u0e32\u0e27\u0e32\u0e07\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01 $10 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e01\u0e33\u0e08\u0e31\u0e14\u0e44\u0e1e\u0e48\u0e17\u0e35\u0e48\u0e41\u0e22\u0e48\u0e21\u0e32\u0e01\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07 16 \u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e44\u0e1e\u0e48\u0e17\u0e35\u0e48\u0e41\u0e22\u0e48\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e46 \u0e2a\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 8 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e07\u0e34\u0e19\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row mB15\">\n<div class=\"col-xs-4 col-sm-3\"> \u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $5.37<\/div>\n<\/p><\/div>\n<div class=\"col-xs-4 col-sm-3\"> \u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $5.35<\/div>\n<\/p><\/div>\n<div class=\"col-xs-4 col-sm-3\"> \u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $4.83<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-3\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.52 <span class=\"red\">(\u0e41\u0e22\u0e01)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"small\">(Exception: In the European No-Hole-Card game, players should NOT split this hand because the dealer might end up with blackjack.<br \/>\n        In the US-style game, the dealer has already checked for blackjack.) <\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 5-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">5<\/div>\n<p>        11 \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d \u0e2a\u0e34\u0e1a<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e01\u0e32\u0e23\u0e25\u0e31\u0e07\u0e40\u0e25\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2a\u0e48\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e41\u0e15\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e01\u0e47\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e1e\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 11 \u0e41\u0e15\u0e49\u0e21\u0e41\u0e25\u0e30\u0e44\u0e1e\u0e48\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e47\u0e19 10 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row mB15\">\n<div class=\"col-xs-6 col-sm-4\"> \u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> $1.18<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\"> \u0e01\u0e32\u0e23\u0e04\u0e39\u0e13\u0e2a\u0e2d\u0e07:<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> $1.78<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.60 <span class=\"red\">(\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"small\">(\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19: \u0e43\u0e19\u0e40\u0e01\u0e21 No-Hole-Card \u0e02\u0e2d\u0e07\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e19\u0e35\u0e49)<\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 4-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">4<\/div>\n<p>        (\u0e40\u0e2d\u0e0b, 7) \u0e1b\u0e30\u0e17\u0e30 \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d 9<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>HIT<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e30\u0e41\u0e1e\u0e07\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48 $0.85 \u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14 \u0e2d\u0e22\u0e48\u0e32\u0e25\u0e31\u0e07\u0e40\u0e25\u0e40\u0e25\u0e22 \u0e01\u0e14\u0e21\u0e31\u0e19\u0e40\u0e25\u0e22.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\">\u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $1.83<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\">\u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $0.98<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$0.85 <span class=\"red\">(\u0e2e\u0e34\u0e15)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 3-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">3<\/div>\n<p>        (8,8) \u0e1e\u0e1a \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d \u0e40\u0e2d\u0e0b<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>\u0e41\u0e22\u0e01<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 6 \u0e17\u0e35\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e15\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e07\u0e40\u0e25\u0e40\u0e14\u0e34\u0e21\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e25\u0e33\u0e1a\u0e32\u0e01.<\/p>\n<p>\u0e21\u0e35\u0e2a\u0e32\u0e21\u0e27\u0e34\u0e18\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e44\u0e1e\u0e48\u0e43\u0e1a\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e41\u0e22\u0e48\u0e21\u0e32\u0e01:<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row mB15\">\n<div class=\"col-xs-4 col-sm-3\">\u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $6.63<\/div>\n<\/p><\/div>\n<div class=\"col-xs-4 col-sm-3\">\u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $5.14<\/div>\n<\/p><\/div>\n<div class=\"col-xs-4 col-sm-3\">\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $3.86<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-3\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$1.28 <span class=\"red\">(\u0e41\u0e22\u0e01)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"small\">(\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19: \u0e43\u0e19\u0e40\u0e01\u0e21 No-Hole-Card \u0e02\u0e2d\u0e07\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e41\u0e22\u0e01\u0e21\u0e37\u0e2d\u0e19\u0e35\u0e49)<\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 2-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">2<\/div>\n<p>        (\u0e40\u0e2d\u0e0b, 6) \u0e1b\u0e30\u0e17\u0e30 \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d 7<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>HIT<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e1c\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e01\u0e47\u0e41\u0e04\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e38\u0e49\u0e19\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e19\u0e49\u0e2d\u0e22\u0e46 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e41\u0e15\u0e48\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e22\u0e32\u0e01\u0e21\u0e32\u0e01 \u0e04\u0e38\u0e13\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e41\u0e1e\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e19\u0e30\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e48\u0e27\u0e44\u0e1e\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e19\u0e35\u0e49 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e07\u0e40\u0e2d\u0e34\u0e0d\u0e17\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e39\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e43\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e08\u0e31\u0e48\u0e27\u0e40\u0e25\u0e22 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e31\u0e07\u0e40\u0e25.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-4\">\u0e22\u0e37\u0e19:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $1.04<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\">\u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> \u0e0a\u0e19\u0e30 1.05 \u0e15\u0e48\u0e2d 0.55<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$1.59 <span class=\"red\">(\u0e2e\u0e34\u0e15)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- Mistake 1-------------------------------------------------><\/p>\n<div class=\"mistake\">\n<div class=\"mistake-title\">\n<div class=\"mistake-number\">1<\/div>\n<p>        (\u0e40\u0e2d\u0e0b,\u0e40\u0e2d\u0e0b) \u0e1e\u0e1a \u0e40\u0e08\u0e49\u0e32\u0e21\u0e37\u0e2d \u0e2a\u0e34\u0e1a<\/p>\n<div class=\"correct-play\"><span class=\"black\">\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07: <\/span>\u0e41\u0e22\u0e01<\/div>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-center\">\n<p>\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e19\u0e35\u0e49\u0e1a\u0e48\u0e2d\u0e22\u0e19\u0e31\u0e01 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e04\u0e23\u0e32\u0e27 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e41\u0e22\u0e01\u0e44\u0e1e\u0e48\u0e40\u0e2d\u0e0b \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e44\u0e1e\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e43\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1c\u0e34\u0e14\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48\u0e41\u0e22\u0e48 \u0e2b\u0e32\u0e01\u0e21\u0e31\u0e19\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e04\u0e38\u0e13 \u0e25\u0e2d\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e44\u0e1e\u0e48 11 \u0e2a\u0e2d\u0e07\u0e43\u0e1a\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e25\u0e2d\u0e07\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e14\u0e39\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e44\u0e1e\u0e48 2 \u0e2b\u0e23\u0e37\u0e2d 12 \u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e30\u0e44\u0e23\u0e02\u0e36\u0e49\u0e19 \u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e34\u0e14\u0e21\u0e32\u0e01\u0e40\u0e25\u0e22 \u0e40\u0e14\u0e34\u0e21\u0e1e\u0e31\u0e19\u0e41\u0e25\u0e30\u0e41\u0e22\u0e01\u0e44\u0e1e\u0e48\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<hr>\n<div class=\"row mB15\">\n<div class=\"col-xs-6 col-sm-4\">\u0e01\u0e32\u0e23\u0e15\u0e35:<\/p>\n<div class=\"red\"><i class=\"fa fa-arrow-down\" aria-hidden=\"true\"><\/i> $0.66<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4\">\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19<\/p>\n<div class=\"text-success\"><i class=\"fa fa-arrow-up\" aria-hidden=\"true\"><\/i> $1.82<\/div>\n<\/p><\/div>\n<div class=\"col-xs-12 col-sm-4\">\n<hr class=\"visible-xs\">\n          \u0e21\u0e31\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<\/p>\n<div class=\"text-success\">$2.48 <span class=\"red\">(\u0e41\u0e22\u0e01)<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"small\">(\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e41\u0e21\u0e49\u0e43\u0e19\u0e40\u0e01\u0e21 No-Hole-Card \u0e41\u0e1a\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e01\u0e32\u0e23\u0e41\u0e22\u0e01\u0e40\u0e2d\u0e0b\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07)<\/div>\n<\/p><\/div>\n<p>    <!-- Mistake end -------------------------------------------------><\/p>\n<p>\n\u0e40\u0e2d\u0e32\u0e25\u0e48\u0e30 \u0e19\u0e31\u0e48\u0e19\u0e41\u0e2b\u0e25\u0e30 \u2018\u0e2b\u0e2d\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e31\u0e1a\u0e2d\u0e32\u0e22\u2019 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e40\u0e2b\u0e47\u0e19 \u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35 $10 \u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e30\u0e2a\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19.\n<\/p>\n<p>\n\u0e2b\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u0e04\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e01\u0e21\u0e19\u0e35\u0e49\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e44\u0e14\u0e49 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u0e08\u0e30\u0e16\u0e39\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e25\u0e47\u0e2d\u0e15\u0e43\u0e19\u0e1e\u0e23\u0e34\u0e1a\u0e15\u0e32 \u0e41\u0e15\u0e48\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e44\u0e21\u0e48\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e14\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e32\u0e2a\u0e34\u0e42\u0e19\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e02\u0e32\u0e14\u0e2a\u0e32\u0e22.\n<\/p>\n<p>\n\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e42\u0e0a\u0e04\u0e14\u0e35, -\u0e40\u0e04\u0e19-\n<\/p>\n<hr>\n<p>\n\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e43\u0e2a\u0e48\u0e43\u0e08\u0e43\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14: \u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e33\u0e19\u0e27\u0e13\u0e43\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e2a\u0e21\u0e21\u0e15\u0e34\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e21 6 \u0e2a\u0e33\u0e23\u0e31\u0e1a S17 DAS \u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e15\u0e49\u0e21 12 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 (\u0e2a\u0e34\u0e1a, 2) \u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e15\u0e49\u0e21 11 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 (5, 6) \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e44\u0e1e\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>If you play blackjack for an hour or two, your results will be pretty unpredictable. You may win a lot, or you may lose a lot. Most of the time, you&#8217;ll be somewhere in between. In the short-term, good luck or bad luck decides whether you&#8217;ll be a net winner or loser. However, if you [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-1499","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top Ten Blackjack Basic Strategy Mistakes<\/title>\n<meta name=\"description\" content=\"The Top Ten Mistakes Made by Blackjack Players.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blackjackinfo.com\/th\/\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e01\u0e25\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top Ten Blackjack Basic Strategy Mistakes\" \/>\n<meta property=\"og:description\" content=\"The Top Ten Mistakes Made by Blackjack Players.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackjackinfo.com\/th\/\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e01\u0e25\/\" \/>\n<meta property=\"og:site_name\" content=\"BlackjackInfo.com\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-22T07:44:46+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/\",\"url\":\"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/\",\"name\":\"Top Ten Blackjack Basic Strategy Mistakes\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\"},\"datePublished\":\"2014-12-23T05:06:06+00:00\",\"dateModified\":\"2018-06-22T07:44:46+00:00\",\"description\":\"The Top Ten Mistakes Made by Blackjack Players.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.blackjackinfo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top Ten Blackjack Basic Strategy Mistakes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackjackinfo.com\/#website\",\"url\":\"https:\/\/www.blackjackinfo.com\/\",\"name\":\"BlackjackInfo.com\",\"description\":\"Because Winning is More Fun!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackjackinfo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04","description":"\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04\u0e17\u0e33\u0e1a\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blackjackinfo.com\/th\/\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e01\u0e25\/","og_locale":"th_TH","og_type":"article","og_title":"Top Ten Blackjack Basic Strategy Mistakes","og_description":"The Top Ten Mistakes Made by Blackjack Players.","og_url":"https:\/\/www.blackjackinfo.com\/th\/\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e01\u0e25\/","og_site_name":"BlackjackInfo.com","article_modified_time":"2018-06-22T07:44:46+00:00","twitter_misc":{"Est. reading time":"5 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/","url":"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/","name":"\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04","isPartOf":{"@id":"https:\/\/www.blackjackinfo.com\/#website"},"datePublished":"2014-12-23T05:06:06+00:00","dateModified":"2018-06-22T07:44:46+00:00","description":"\u0e2a\u0e34\u0e1a\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e41\u0e1a\u0e25\u0e47\u0e04\u0e41\u0e08\u0e47\u0e04\u0e17\u0e33\u0e1a\u0e48\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14.","breadcrumb":{"@id":"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackjackinfo.com\/top-ten-blackjack-basic-strategy-mistakes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.blackjackinfo.com\/"},{"@type":"ListItem","position":2,"name":"Top Ten Blackjack Basic Strategy Mistakes"}]},{"@type":"WebSite","@id":"https:\/\/www.blackjackinfo.com\/#website","url":"https:\/\/www.blackjackinfo.com\/","name":"BlackjackInfo.com","description":"\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e0a\u0e19\u0e30\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e27\u0e48\u0e32!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackjackinfo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/pages\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":14,"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/pages\/1499\/revisions"}],"predecessor-version":[{"id":3729,"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/pages\/1499\/revisions\/3729"}],"wp:attachment":[{"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackjackinfo.com\/th\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}